{"id":357,"date":"2015-11-05T23:00:00","date_gmt":"2015-11-05T23:00:00","guid":{"rendered":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-campania\/evento\/i-giovani-del-club-alpino-italiano-alla-scoperta-di-minerali-e-rocce-2\/"},"modified":"2024-11-15T16:24:52","modified_gmt":"2024-11-15T16:24:52","slug":"i-giovani-del-club-alpino-italiano-alla-scoperta-di-minerali-e-rocce-2","status":"publish","type":"tribe_events","link":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-campania\/evento\/i-giovani-del-club-alpino-italiano-alla-scoperta-di-minerali-e-rocce-2\/","title":{"rendered":"&#8220;i Giovani Del Club Alpino Italiano Alla Scoperta Di Minerali E Rocce&#8221;Laboratorio Didattico Itinerante"},"content":{"rendered":"<p style=\"text-align: justify;\">Nell&#8217;ambito del Progetto &#8220;I giovani del Club Alpino Italiano alla scoperta di minerali e rocce&#8221;, con il contributo ed il patrocinio della Societ\u00e0 Italiana<br \/>\n    di Mineralogia e Petrologia, verr\u00e0 svolta una serie di attivit\u00e0 con lo scopo di fare conoscere agli aquilotti i minerali e le rocce della Terra, e<br \/>\n    di insegnare loro a riconoscerli e&nbsp; a scoprirne la &#8220;magia&#8221; in maniera diretta e divertente.<\/p>\n<p style=\"text-align: justify;\">Le attivit\u00e0 comprenderanno un laboratorio didattico itinerante, che verr\u00e0 offerto a tre sedi, ed un&#8217;escursione intersezionale, in cui i ragazzi potranno<br \/>\n    osservare e conoscere l&#8217;ambiente geologico e raccogliere minerali e rocce per allestire collezioni in sede.<\/p>\n<p>A cura di&nbsp;Rosalda Punturo<\/p>\n<p><strong><em>Quando e dove:<\/em><\/strong>\n<\/p>\n<p><strong><em> -\/Venerdi 6 novembre 2015 ore 18.00-20.00 sede C.A.I. di Acireale (via Dafnica 26, Acireale)<\/em><\/strong>\n<\/p>\n<p><strong><em>-\/Marted\u00ec 17 novembre 2015 ore 18.00-20.00 sede C.A.I. di Catania (via Messina 593a, Catania)<\/em><\/strong>\n<\/p>\n<p><strong><em>-\/Gioved\u00ec 19 novembre 2015 ore 18.00-20.00 sede C.A.I. di Pedara (via Pizzoferro 5, Pedara)<\/em><\/strong>\n<\/p>\n<p><strong><em>Escursione intersezionale: domenica 29 novembre. Localit\u00e0: Monte Grosso-Gemmellaro (Etna)<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell&#8217;ambito del Progetto &#8220;I giovani del Club Alpino Italiano alla scoperta di minerali e rocce&#8221;, con il contributo ed il patrocinio della Societ\u00e0 Italiana di Mineralogia e Petrologia, verr\u00e0 svolta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":358,"comment_status":"closed","ping_status":"open","template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[8],"tribe_events_cat":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-campania\/wp-json\/wp\/v2\/tribe_events\/357"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-campania\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-campania\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-campania\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-campania\/wp-json\/wp\/v2\/comments?post=357"}],"version-history":[{"count":2,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-campania\/wp-json\/wp\/v2\/tribe_events\/357\/revisions"}],"predecessor-version":[{"id":540,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-campania\/wp-json\/wp\/v2\/tribe_events\/357\/revisions\/540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-campania\/wp-json\/wp\/v2\/media\/358"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-campania\/wp-json\/wp\/v2\/media?parent=357"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-campania\/wp-json\/wp\/v2\/tags?post=357"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-campania\/wp-json\/wp\/v2\/tribe_events_cat?post=357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}