{"id":361,"date":"2015-10-10T22:00:00","date_gmt":"2015-10-10T22:00:00","guid":{"rendered":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-lazio\/evento\/otto-lazio-giornata-per-lambiente-raduno-intersezionale-a-preta-di-amatrice-ri-11-ottobre-2015\/"},"modified":"2024-11-15T17:39:39","modified_gmt":"2024-11-15T17:39:39","slug":"otto-lazio-giornata-per-lambiente-raduno-intersezionale-a-preta-di-amatrice-ri-11-ottobre-2015","status":"publish","type":"tribe_events","link":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-lazio\/evento\/otto-lazio-giornata-per-lambiente-raduno-intersezionale-a-preta-di-amatrice-ri-11-ottobre-2015\/","title":{"rendered":"Otto Lazio: Giornata Per L&#8217;ambiente &#8211; Raduno Intersezionale A Preta Di Amatrice (ri) &#8211; 11 Ottobre 2015"},"content":{"rendered":"<h2 style=\"font-style: italic; text-align: center;\"><strong>GIORNATA PER L&#8217;AMBIENTE<\/strong><\/h2>\n<h2 style=\"font-style: italic; text-align: center;\">Sentieri, Ambiente e Nuove Generazioni<\/h2>\n<h2 style=\"font-style: italic; text-align: center;\">Preta di Amatrice (RI) &#8211; 11 ottobre 2015<\/h2>\n<h2 style=\"font-style: italic; text-align: center;\">Raduno Intersezionale<\/h2>\n<h2 style=\"font-style: italic; text-align: center;\">&#8220;Una giornata con i ragazzi dell&#8217;Alpinismo Giovanile delle sezioni\u00a0CAI del Lazio, per camminare, conoscere e rispettare la natura\u00a0uniti dall&#8217;amore per la montagna&#8221;<\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"font-style: italic; text-align: center;\">PROGRAMMA<\/h2>\n<h2 style=\"font-style: italic;\">\uf0fc 09:30 ritrovo a PRETA<br \/>\n\uf0fc 10:00 escursione guidata alla VALLE DI SELVA GRANDE (E) in\u00a0collaborazione con il Gruppo TAM della Sezione CAI di Amatrice<br \/>\n\uf0fc 14:30 pranzo per tutti a Preta presso il Punto Informativo\u00a0Sezione CAI Amatrice<\/h2>\n<h2 style=\"font-style: italic;\">A seguire attivit\u00e0 &#8220;ORTO BOTANICO MONTI DELLA LAGA&#8221;\u00a0della Sezione CAI Amatrice. Merenda e saluti<\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"font-style: italic;\">PER INFORMAZIONI<\/h2>\n<h2 style=\"font-style: italic;\"><a href=\"mailto:presidente@caiamatrice.it?subject=Richiesta%20info%20giornata%20ambiente\">presidente@caiamatrice.it<\/a><\/h2>\n<h2 style=\"font-style: italic;\">mob. 3394731194<\/h2>\n<h2 style=\"font-style: italic;\"><a href=\"http:\/\/www.caiamatrice.it\" target=\"_blank\" rel=\"noopener\">www.caiamatrice.it<\/a><\/h2>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GIORNATA PER L&#8217;AMBIENTE Sentieri, Ambiente e Nuove Generazioni Preta di Amatrice (RI) &#8211; 11 ottobre 2015 Raduno Intersezionale &#8220;Una giornata con i ragazzi dell&#8217;Alpinismo Giovanile delle sezioni\u00a0CAI del Lazio, per [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":362,"comment_status":"closed","ping_status":"open","template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[7],"tribe_events_cat":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-lazio\/wp-json\/wp\/v2\/tribe_events\/361"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-lazio\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-lazio\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-lazio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-lazio\/wp-json\/wp\/v2\/comments?post=361"}],"version-history":[{"count":1,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-lazio\/wp-json\/wp\/v2\/tribe_events\/361\/revisions"}],"predecessor-version":[{"id":464,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-lazio\/wp-json\/wp\/v2\/tribe_events\/361\/revisions\/464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-lazio\/wp-json\/wp\/v2\/media\/362"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-lazio\/wp-json\/wp\/v2\/media?parent=361"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-lazio\/wp-json\/wp\/v2\/tags?post=361"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-alpinismo-giovanile-lazio\/wp-json\/wp\/v2\/tribe_events_cat?post=361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}