{"id":169,"date":"2023-05-21T19:03:44","date_gmt":"2023-05-21T19:03:44","guid":{"rendered":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/evento\/visita-agli-impianti-della-diga-del-vajont\/"},"modified":"2024-12-13T15:38:17","modified_gmt":"2024-12-13T15:38:17","slug":"visita-agli-impianti-della-diga-del-vajont","status":"publish","type":"tribe_events","link":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/evento\/visita-agli-impianti-della-diga-del-vajont\/","title":{"rendered":"Visita agli Impianti della Diga del Vajont"},"content":{"rendered":"<figure id=\"attachment_68859\" aria-describedby=\"caption-attachment-68859\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" id=\"longdesc-return-68859\" class=\"size-medium wp-image-68859\" src=\"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/100\/2024\/12\/DSCN8658.jpg\" alt=\"DigaDelVajont\" width=\"300\" height=\"225\" longdesc=\"https:\/\/archicai.local?longdesc=68859&amp;referrer=0\" title=\"\"><figcaption id=\"caption-attachment-68859\" class=\"wp-caption-text\">Il ponte tubo e la diga del Vajont<\/figcaption><\/figure>\n<p>Domenica 14 maggio 2023 si \u00e8 svolta, a cura del gruppo TAM della Sezione CAI di Mestre, una vista agli impianti della diga del Vajont e dei luoghi della frana del Monte Toc. L\u2019occasione, davvero unica, ha consentito a 35 partecipanti di visitare la diga nel suo complesso accedendo anche a zone che normalmente non sono aperte al pubblico. Ci\u00f2 \u00e8 stato reso possibile grazie alla disponibilit\u00e0 concessa in via eccezionale da Enel Energia e dall\u2019attivit\u00e0 di raccordo svolta dal socio ORTAM Antonio Calabretta appassionato di dighe e di impianti per la produzione dell&#8217;energia rinnovabile e dal prof. Roberto Francese, geofisico e glaciologo dell&#8217;Universit\u00e0 di Parma e membro dell\u2019Istituto Nazionale di Oceanografia e Geofisica applicata di Trieste, che ha studiato per molti anni la zona del Vajont e le cause della frana ed ha collaborato anche a diversi documentari sull\u2019argomento, tra i quali quello mandato in onda su La7 disponibile al seguente link:<\/p>\n<p><a href=\"https:\/\/www.la7.it\/atlantide\/rivedila7\/atlantide-vajont-la-lezione-dimenticata-16-10-2021-403111\" target=\"_blank\" rel=\"noopener\">https:\/\/www.la7.it\/atlantide\/rivedila7\/atlantide-vajont-la-lezione-dimenticata-16-10-2021-403111<\/a><\/p>\n<p>Nel 1960, quando fu ultimata la sua costruzione la diga era la pi\u00f9 alta del mondo con i suoi 262 metri circa di altezza, oggi \u00e8 l\u2019ottava.<\/p>\n<p>Partendo dalla vecchia strada di accesso, oggi chiusa al traffico, accompagnati dal personale di ENEL Green Power i partecipanti sono passati sopra il ponte di ferro (il \u201cponte-tubo\u201d) che unisce le due pareti opposte della forra del Vajont e sono stati visitati alcuni locali di servizio della diga sul lato orografico sinistro, normalmente inaccessibili al pubblico, tra cui il locale dove risiede il pendolo sismico uno strumento sensibilissimo, che rileva i movimenti sismici.<\/p>\n<p>A Casso da una terrazza panoramica costruita sulla vecchia scuola elementare lambita dalla terribile onda d\u2019acqua provocata dal cedimento del monte Toc il 9 ottobre 1963 \u00e8 stato possibile vedere l\u2019intero corpo di frana con il suo caratteristico profilo a M per comprendere maggiormente gli effetti devastanti provocatisi su tutta la valle, ed i massi incredibilmente arrivati fin lass\u00f9 in paese grazie all\u2019imponente spostamento d\u2019aria creato dalla frana. Accompagnati anche da una guida del Parco delle Dolomiti Friulane il gruppo risalendo verso il sito della frana ha potuto osservare nel bosco vecchio (ovvero la parte di bosco sopravvissuto alla frana stessa) alcuni alberi che portano ancora oggi il segno del terribile evento sul loro tronco fortemente curvato, infine si \u00e8 giunti ad attraversare il coronamento sommitale della diga.<\/p>\n<p>Il venerd\u00ec precedente si \u00e8 altres\u00ec svolta una serata introduttiva all\u2019uscita presso la sede sezionale del Cai di Mestre, durante la quale sono state illustrate le caratteristiche della diga, la storia della tragedia del Vajont e le cause della franta del Monte Toc. Durante la presentazione \u00e8 stato mostrato del materiale fotografico originale e normalmente non accessibile al pubblico. L\u2019intervento del Prof. Francese \u00e8 stato reso altres\u00ec accessibile on line vista la diversificata provenienza dei partecipanti non solo dal Veneto ma anche dal Friuli Venezia Giulia.<\/p>\n<p>L&#8217;uscita rientrava nel programma delle iniziative del gruppo TAM della sezione di Mestre e si proponeva come continuazione ideale della visita fatta lo scorso anno agli impianti idroelettrici del Cismon nel Primiero (TN).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 14 maggio 2023 si \u00e8 svolta, a cura del gruppo TAM della Sezione CAI di Mestre, una vista agli impianti della diga del Vajont e dei luoghi della frana [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[7],"tribe_events_cat":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events\/169"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=169"}],"version-history":[{"count":2,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events\/169\/revisions"}],"predecessor-version":[{"id":252,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events\/169\/revisions\/252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/36"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=169"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=169"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events_cat?post=169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}