{"id":180,"date":"2022-06-21T16:57:48","date_gmt":"2022-06-21T16:57:48","guid":{"rendered":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/evento\/la-potenza-dellacqua-al-servizio-delluomo-6-maggio-2022\/"},"modified":"2024-12-13T15:36:56","modified_gmt":"2024-12-13T15:36:56","slug":"la-potenza-dellacqua-al-servizio-delluomo-6-maggio-2022","status":"publish","type":"tribe_events","link":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/evento\/la-potenza-dellacqua-al-servizio-delluomo-6-maggio-2022\/","title":{"rendered":"La Potenza dell&#8217;acqua al Servizio dell&#8217;uomo"},"content":{"rendered":"<h1>La potenza dell&#8217;acqua al servizio dell&#8217;uomo &#8211; 6 maggio 2022<\/h1>\n<p>Programma della giornata:<\/p>\n<p><em>&#8211; ore 9.30 inizio visita della diga di Val Schener, sita ai confini del comune di Sovramonte (BL). Coordinate:\u00a0<\/em><a href=\"https:\/\/goo.gl\/maps\/BWin8YKwBXwHVEsD8\" target=\"_blank\" rel=\"noopener\"><em>https:\/\/goo.gl\/maps\/BWin8YKwBXwHVEsD8<\/em><\/a><\/p>\n<p><em>&#8211; ore 11 partenza per la Centrale Elettrica di Caoria, sita in\u00a0Localit\u00e0 Volpi, 202, 38050 Canal San Bovo (TN). Coordinate:<\/em><em>\u00a0<\/em><a href=\"https:\/\/goo.gl\/maps\/4hDqL1KkcSgmwfdBA\" target=\"_blank\" rel=\"noopener\"><em>https:\/\/goo.gl\/maps\/4hDqL1KkcSgmwfdBA<\/em><\/a><\/p>\n<p><em>&#8211; ore 11.30 visita impianti della centrale idroelettrica di Caoria..<\/em><\/p>\n<p><em>&#8211; ore 15 inizio visita guidata di Villa Welsperg (centro visite del Parco di Paneveggio), sita in val Canali, Tonadico (TN). Coordinate:\u00a0<\/em><a href=\"https:\/\/goo.gl\/maps\/TQqyWdmFZZwaNoPG6\" target=\"_blank\" rel=\"noopener\"><em>https:\/\/goo.gl\/maps\/TQqyWdmFZZwaNoPG6<\/em><\/a><em>.<\/em><\/p>\n<p><em>Si visiter\u00e0 il giardino e i locali interni, in particolare la Fisioteca, che comprende una xiloteca, una litoteca, una lichenoteca e molto altro.\u00a0<\/em><\/p>\n<p><em>&#8211; ore 17: fine della visita.\u00a0<\/em><\/p>\n<p><a href=\"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/100\/2024\/12\/Idroelettrico_Primiero.pdf\" target=\"_blank\" rel=\"noopener\">Presentazione<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La potenza dell&#8217;acqua al servizio dell&#8217;uomo &#8211; 6 maggio 2022 Programma della giornata: &#8211; ore 9.30 inizio visita della diga di Val Schener, sita ai confini del comune di Sovramonte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[7],"tribe_events_cat":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events\/180"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=180"}],"version-history":[{"count":3,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events\/180\/revisions"}],"predecessor-version":[{"id":245,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events\/180\/revisions\/245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/36"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=180"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=180"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events_cat?post=180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}