{"id":185,"date":"2022-02-17T21:37:56","date_gmt":"2022-02-17T21:37:56","guid":{"rendered":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/evento\/vivere-lambiente-2017-xxi-anno\/"},"modified":"2024-12-13T15:36:33","modified_gmt":"2024-12-13T15:36:33","slug":"vivere-lambiente-2017-xxi-anno","status":"publish","type":"tribe_events","link":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/evento\/vivere-lambiente-2017-xxi-anno\/","title":{"rendered":"Vivere l\u2019Ambiente 2017 \u2013 XXI Anno"},"content":{"rendered":"<p><strong>VIVERE L\u2019AMBIENTE 2017 \u2013 XXI ANNO<\/strong><\/p>\n<p>I protagonisti dell\u2019attivit\u00e0 di quest\u2019anno saranno i\u00a0<em><strong>Monumenti naturali<\/strong><\/em>, un tema che ci far\u00e0 spaziare tra bellezze e particolarit\u00e0 della natura che incuriosiscono e sorprendono e per le quali le regioni possono attivare delle tutele ambientali per conservarli e tramandarli.<\/p>\n<p>Programma generale: 3 serate 10 uscite\u00a0<a title=\"ProgrammaVLA2017\" href=\"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/100\/2024\/12\/vla2017.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">VIVERE L\u2019AMBIENTE 2017 programma generale<\/a><\/p>\n<p>Uscita del 9 aprile\u00a0<a title=\"PontDeValDarc\" href=\"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/100\/2024\/12\/VLA2017-U01-pontdevaldarc.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Pont de Val D\u2019arc<\/a><\/p>\n<p>Uscita del 14 maggio\u00a0<a href=\"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/100\/2024\/12\/VLA2017-U02-FUSINE.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Laghi di Fusine<\/a><\/p>\n<p>Uscita del 28 maggio\u00a0<a title=\"U03VACCARESSE\" href=\"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/100\/2024\/12\/VLA2017-U03-VACCARESSE.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Torre e ponte di malga Vaccaresse<\/a><\/p>\n<p>Uscita del 18 giugno\u00a0<a href=\"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/100\/2024\/12\/VLA2017-U04-FORRAPASSIRIO.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Gole del Passirio<\/a><\/p>\n<p>Uscita del 8 e 9 luglio\u00a0<a title=\"U03VACCARESSE\" href=\"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/100\/2024\/12\/VLA2017-U05-KRIMML.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Parco degli alti Tauri \u2013 Cascate di Krimml<\/a><\/p>\n<p>Uscita del 9 e 10 settembre, al\u00a0<a title=\"VLA2017-Marmolada\" href=\"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/100\/2024\/12\/VLA2017-U06-Marmolada.pdf\" target=\"_blank\" rel=\"noopener\">Ghiacciaio della Marmolada<\/a>\u00a0 un imponente monumento naturale,\u00a0per osservare il ghiacciaio e le forme collegate al glacialismo passato e presente.\u00a0Partendo\u00a0da Villetta Maria l\u2019itinerario seguir\u00e0 il bellissimo Sentiero delle Marmitte e poi s\u00f9 fino\u00a0al Pian dei Fiacconi.\u00a0Notte in rifugio. Il giorno dopo raggiungeremo il fronte del ghiacciaio per una osservazione ravvicinata.<\/p>\n<p>Uscita del 5 novembre\u00a0\u00a0<a title=\"U03VACCARESSE\" href=\"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/100\/2024\/12\/VLA2017-U10-BUSDELBUSON-Feltre.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Bus del Buson<\/a><\/p>\n<hr id=\"system-readmore\" class=\"mceItemReadMore\" \/>\n<p>Ma cosa sono i\u00a0<em>Monumenti naturali<\/em>?<\/p>\n<p>I\u00a0<em>Monumenti naturali<\/em>\u00a0sono suddivisi in due categorie:\u00a0geologici e\u00a0botanici.<br \/>\nSono denominati\u00a0<em>Monumenti naturali<\/em>\u00a0singoli elementi o piccole superfici di pregio dell\u2019ambiente naturale, ad esempio alberi, sorgenti, cascate, laghi alpini, formazioni rocciose e di ghiaccio, caverne, giacimenti minerari e fossili, affioramenti geologici e elementi geomorfologici, che devono essere conservati nella loro integrit\u00e0.<br \/>\nQuesti fenomeni sono il risultato dell\u2019azione del vento, dell\u2019acqua, del ghiaccio, del carsismo o di un clima severo. Situazioni che, con i tempi della terra, hanno determinato la modificazione della morfologia del territorio o di una specie vegetale, portando alla formazione di piramidi di terra, grotte, rocce dalle forme singolari (marmitte, pinnacoli, torri), enormi blocchi di pietra trasportati dal movimento dei ghiacciai lontano dai siti di origine (massi erratici) e cascate, forre, valli o imponenti alberi contorti.<\/p>\n<p>Nel nostro programma abbiamo voluto rappresentarli un po\u2019 tutti ma potremo dare solo un piccolo assaggio di quanto di spettacolare la natura ci regala.<\/p>\n<p>Star\u00e0 poi ad ognuno\/a di noi cercarne altri, per ora per\u00f2 contiamo di avervi con noi per iniziare assieme questo gioco di scoperta.<\/p>\n<p><em>Il Gruppo Operativo 2017 di Vivere l\u2019Ambiente<\/em><\/p>\n<p><em>Maria Grazia, Maria Rosa, Guido, Fiorella, Massimo, Fabrizio, Giorgio, Lidia, Lia, Maurizio, Enzo, ELisabetta, Andrea, Daniela, Barbara,<\/em><em><br \/>\nElisa, Diana, Zoe, Elena, Filippo, Fiorenza, Antonio, Renato, Lorenzo, Nadia.<\/em><\/p>\n<p><em><a href=\"http:\/\/www.viverelambiente.it\/\" target=\"_blank\" rel=\"noopener\">www.viverelambiente.it<\/a><\/em><\/p>\n<p><em>seguici su\u00a0<\/em><em>facebook\u00a0<a href=\"https:\/\/www.facebook.com\/groups\/109724132399296\/?fref=ts\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/groups\/109724132399296\/?fref=ts<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIVERE L\u2019AMBIENTE 2017 \u2013 XXI ANNO I protagonisti dell\u2019attivit\u00e0 di quest\u2019anno saranno i\u00a0Monumenti naturali, un tema che ci far\u00e0 spaziare tra bellezze e particolarit\u00e0 della natura che incuriosiscono e sorprendono [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[7,9],"tribe_events_cat":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events\/185"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=185"}],"version-history":[{"count":2,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events\/185\/revisions"}],"predecessor-version":[{"id":242,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events\/185\/revisions\/242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/36"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=185"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=185"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events_cat?post=185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}