{"id":746,"date":"2025-09-16T19:33:30","date_gmt":"2025-09-16T19:33:30","guid":{"rendered":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/?post_type=tribe_events&#038;p=746"},"modified":"2025-09-16T19:41:04","modified_gmt":"2025-09-16T19:41:04","slug":"corso-di-aggiornamento-per-operatori-tam-2025","status":"publish","type":"tribe_events","link":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/evento\/corso-di-aggiornamento-per-operatori-tam-2025\/","title":{"rendered":"Corso di aggiornamento per Operatori TAM 2025"},"content":{"rendered":"<h2 style=\"text-align: center;\"><span style=\"color: #ff0000;\"><strong>Claut (PN), sabato 18 e domenica 19 ottobre 2025<\/strong><\/span><br \/>\n<a href=\"https:\/\/maps.app.goo.gl\/EzZz21NqSj7YjVi59\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\"><strong>Sala del Consiglio di Claut<\/strong><\/span><\/a><br \/>\n<span style=\"color: #0000ff;\"><strong>\u201c<\/strong><\/span><span style=\"color: #0000ff;\"><strong>Tutela degli ambienti carsici: sistemi fondamentali nel ciclo dell\u2019acqua e scrigni di conoscenza scientifica<\/strong><\/span><span style=\"color: #0000ff;\"><strong>\u201d<\/strong><\/span><\/h2>\n<p>La tutela degli ambienti carsici \u00e8 essenziale per diverse ragioni. I sistemi carsici sono fondamentali per la gestione delle risorse idriche, la conservazione della biodiversit\u00e0, la protezione dei paesaggi e la loro importanza storico-culturale. Il carsismo \u00e8 un fenomeno geologico che si sviluppa su rocce carbonatiche e produce caratteristiche paesaggistiche uniche, come doline, campi solcati, grotte con corsi d&#8217;acqua sotterranei.<\/p>\n<p>La tutela degli ambienti carsici \u00e8 fondamentale per la conservazione delle risorse idriche, per la protezione della biodiversit\u00e0 e per la valorizzazione del patrimonio culturale e scientifico.<\/p>\n<p style=\"text-align: center;\"><strong>Il corso di aggiornamento TAM 2025 \u00e8 rivolto a tutti i soci CAI interessati alle tematiche trattate, con le medesime modalit\u00e0 degli operatori TAM (Titolati).<\/strong><br \/>\n<em>Sabato 18\/10\/2025 Corso di Formazione\/Aggiornamento &#8211; Domenica 19\/10\/2025 Uscita in ambiente<\/em><\/p>\n<p><strong><a href=\"https:\/\/archivio.cai.it\/wp-content\/uploads\/2025\/09\/Programma_aggTAM-VFG2025.pdf\" target=\"_blank\" rel=\"noopener\">Programma_aggTAM-VFG2025<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/archivio.cai.it\/wp-content\/uploads\/2025\/09\/Locandina_aggTAM2025.pdf\" target=\"_blank\" rel=\"noopener\">Locandina_aggTAM2025<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/forms.gle\/9dXxaovYXjwFxLXXA\" target=\"_blank\" rel=\"noopener\">Modulo di iscrizione<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Claut (PN), sabato 18 e domenica 19 ottobre 2025 Sala del Consiglio di Claut \u201cTutela degli ambienti carsici: sistemi fondamentali nel ciclo dell\u2019acqua e scrigni di conoscenza scientifica\u201d La tutela [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":741,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[12],"tribe_events_cat":[11],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events\/746"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=746"}],"version-history":[{"count":2,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events\/746\/revisions"}],"predecessor-version":[{"id":750,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events\/746\/revisions\/750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/741"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=746"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=746"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-centrale-tutela-ambiente-montano-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tribe_events_cat?post=746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}