{"id":464,"date":"2025-07-08T13:18:55","date_gmt":"2025-07-08T13:18:55","guid":{"rendered":"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/?p=464"},"modified":"2025-07-30T13:45:08","modified_gmt":"2025-07-30T13:45:08","slug":"le-zecche-mercoledi-16-luglio-2025-ore-20-45-sala-consiliare-calalzo-di-cadore-bl","status":"publish","type":"post","link":"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/2025\/07\/le-zecche-mercoledi-16-luglio-2025-ore-20-45-sala-consiliare-calalzo-di-cadore-bl\/","title":{"rendered":"LE ZECCHE, MERCOLED\u00cc 16 LUGLIO 2025 ORE 20.45, SALA CONSILIARE CALALZO DI CADORE (BL)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"1080\" src=\"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/134\/2025\/07\/photo-2025-07-08-14-36-30-735x1080.webp\" alt=\"- CAI\" class=\"wp-image-465\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/134\/2025\/07\/photo-2025-07-08-14-36-30-735x1080.webp 735w, https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/134\/2025\/07\/photo-2025-07-08-14-36-30-490x720.webp 490w, https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/134\/2025\/07\/photo-2025-07-08-14-36-30-768x1128.webp 768w, https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-content\/uploads\/sites\/134\/2025\/07\/photo-2025-07-08-14-36-30.webp 945w\" sizes=\"(max-width: 735px) 100vw, 735px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":351,"featured_media":465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/464"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/351"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=464"}],"version-history":[{"count":2,"href":"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/464\/revisions"}],"predecessor-version":[{"id":467,"href":"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/464\/revisions\/467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/465"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-medica-veneto-friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}