{"id":209,"date":"2023-11-09T10:20:26","date_gmt":"2023-11-09T10:20:26","guid":{"rendered":"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/2023\/11\/18-corso-esame-per-istruttori-nazionali-di-arrampicata-libera-inal\/"},"modified":"2024-12-13T16:27:56","modified_gmt":"2024-12-13T16:27:56","slug":"18-corso-esame-per-istruttori-nazionali-di-arrampicata-libera-inal","status":"publish","type":"post","link":"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/2023\/11\/18-corso-esame-per-istruttori-nazionali-di-arrampicata-libera-inal\/","title":{"rendered":"18\u00b0 Corso\/esame INAL"},"content":{"rendered":"<h2><span style=\"color: #0000ff\"><strong>18\u00b0 CORSO\/ESAME PER ISTRUTTORI NAZIONALI DI ARRAMPICATA LIBERA (INAL)<\/strong><\/span><\/h2>\n<p>La Scuola Centrale di Alpinismo e Arrampicata Libera (SCA), su mandato della Commissione Nazionale Scuole di Alpinismo, Scialpinismo e Arrampicata Libera del Club Alpino Italiano, organizza nel periodo novembre 2023 \u2013 novembre 2024 il 18\u00b0 Corso\/Esame per Istruttori Nazionali di Arrampicata Libera.<\/p>\n<p>Il Corso sar\u00e0 diretto da Gianpietro Rossi (INAL, INA, SCA). Ciascun modulo in cui \u00e8 articolato il Corso avr\u00e0 un direttore responsabile e il corpo istruttori, in numero adeguato alle specifiche esigenze, sar\u00e0 formato da Istruttori Nazionali della SCA.<\/p>\n<p>Per l\u2019ammissione al Corso ogni candidato dovr\u00e0 presentare domanda, redatta sugli appositi moduli, debitamente firmati dal Direttore della Scuola e dal Presidente della Sezione di appartenenza, dovranno essere inviati in formato elettronico (PDF) alla segreteria della Commissione Nazionale delle Scuole di Alpinismo, Scialpinismo e Arrampicata Libera del CAI (all\u2019attenzione del Sig. Paolo Veronelli, sede CAI Centrale; <a href=\"mailto:segreteria@cnsasa.it\">segreteria@cnsasa.it<\/a>) entro e non oltre il <span style=\"color: #0000ff\"><strong>16 luglio 2023<\/strong><\/span>.<br \/>\nIl curriculum dell\u2019attivit\u00e0 personale e didattica dovr\u00e0 anche essere compilato utilizzando il file in formato Excel opportunamente predisposto e disponibile sul sito della CNSASA, senza alterarne il formato, allegandolo alla domanda di iscrizione.<\/p>\n<p>Qui nel seguito potrete scaricare il Bando e le Linee guida per la partecipazione (Regolamento Corso I.N.A.L.); potrete inoltre scaricare il Modulo per inviare la Domanda di Partecipazione e quello per la compilazione dell\u2019Attivit\u00e0 (in formato Excel).<\/p>\n<p><em>Il Presidente C.N.S.A.SA.<br \/>\nMauro Loss, I.N.A.\u00a0 I.N.A.L\u00a0 I.N.S.A.<\/em><\/p>\n<p>&nbsp;<\/p>\n<table style=\"height: 130px\" width=\"829\">\n<tbody>\n<tr>\n<td width=\"180\">Bando del Corso:<\/td>\n<td width=\"508\"><a href=\"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-content\/uploads\/sites\/101\/2024\/12\/Bando_corso_esame_INAL_2023.pdf\" target=\"_blank\" rel=\"noopener\">Bando INAL 2023<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"180\">Linee guida:<\/td>\n<td width=\"508\"><a href=\"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-content\/uploads\/sites\/101\/2024\/12\/Regolamento_CORSO_INAL.pdf\" target=\"_blank\" rel=\"noopener\">Regolamento CORSO INAL 2023<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"180\">Domanda di ammissione:<\/td>\n<td width=\"508\"><a href=\"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-content\/uploads\/sites\/101\/2024\/12\/Modulo-Domanda-IN.pdf\" target=\"_blank\" rel=\"noopener\">Modulo Domanda INAL 2023<\/a><\/td>\n<\/tr>\n<tr>\n<td width=\"180\">Curriculum vitae:<\/td>\n<td width=\"508\"><a href=\"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-content\/uploads\/sites\/101\/2024\/12\/Curriculum_Attivita_INA-INAL_2023-2024.xls\" download target=\"_blank\" rel=\"noopener\">Curriculum Attivit\u00e0 INA INAL 2023<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>18\u00b0 CORSO\/ESAME PER ISTRUTTORI NAZIONALI DI ARRAMPICATA LIBERA (INAL) La Scuola Centrale di Alpinismo e Arrampicata Libera (SCA), su mandato della Commissione Nazionale Scuole di Alpinismo, Scialpinismo e Arrampicata Libera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":210,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-json\/wp\/v2\/posts\/209"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-json\/wp\/v2\/comments?post=209"}],"version-history":[{"count":1,"href":"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-json\/wp\/v2\/posts\/209\/revisions"}],"predecessor-version":[{"id":293,"href":"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-json\/wp\/v2\/posts\/209\/revisions\/293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-json\/wp\/v2\/media\/210"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-json\/wp\/v2\/media?parent=209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-json\/wp\/v2\/categories?post=209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/commissione-nazionale-scuole-alpinismo-scialpinismo-arrampicata-libera\/wp-json\/wp\/v2\/tags?post=209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}