{"id":7865,"date":"2025-11-07T14:25:25","date_gmt":"2025-11-07T14:25:25","guid":{"rendered":"https:\/\/organizzazione.cai.it\/gr-toscana\/?p=7865"},"modified":"2025-11-07T14:25:25","modified_gmt":"2025-11-07T14:25:25","slug":"il-cai-si-pronuncia-sui-piani-attuativi-dei-bacini-estrattivi-in-apuane","status":"publish","type":"post","link":"https:\/\/organizzazione.cai.it\/gr-toscana\/2025\/11\/il-cai-si-pronuncia-sui-piani-attuativi-dei-bacini-estrattivi-in-apuane\/","title":{"rendered":"Il CAI si pronuncia sui Piani Attuativi dei Bacini Estrattivi in Apuane"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Il Club Alpino, come CAI Toscana, Commissione Regionale Tutela Ambiente Montano e sezione di Massa, si esprime con un comunicato congiunto su quanto approvato dal Comune di Massa in merito ai P.A.B.E., piani attuativi dei bacini estrattivi. L&#8217;amministrazione ha ignorato ogni nostra osservazione tesa alla salvaguarda dell&#8217;ecosistema apuano. Il nostro sforzo va adesso a far si che venga definitivamente chiusa, visto il fallimento  della societ\u00e0 che l&#8217;aveva in gestione, la Cava Focolaccia, dove da anni si sta mangiando l&#8217;omonimo passo e territorio contiguo. L&#8217;appello \u00e8 rivolto al Parco delle Apuane, alla Regione Toscana e alle province e comuni interessati. E chiediamo ascolto.<\/p>\n\n\n\n<p>al link potete leggere il Comunicato per intero.<\/p>\n\n\n\n<p><a href=\"https:\/\/organizzazione.cai.it\/gr-toscana\/wp-content\/uploads\/sites\/66\/2025\/11\/Apuane-Ecosistema-o-polo-di-sfruttamento.pdf\">https:\/\/organizzazione.cai.it\/gr-toscana\/wp-content\/uploads\/sites\/66\/2025\/11\/Apuane-Ecosistema-o-polo-di-sfruttamento.pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Club Alpino, come CAI Toscana, Commissione Regionale Tutela Ambiente Montano e sezione di Massa, si esprime con un comunicato congiunto su quanto approvato dal Comune di Massa in merito [&hellip;]<\/p>\n","protected":false},"author":187,"featured_media":36,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/gr-toscana\/wp-json\/wp\/v2\/posts\/7865"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/gr-toscana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/gr-toscana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/gr-toscana\/wp-json\/wp\/v2\/users\/187"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/gr-toscana\/wp-json\/wp\/v2\/comments?post=7865"}],"version-history":[{"count":1,"href":"https:\/\/organizzazione.cai.it\/gr-toscana\/wp-json\/wp\/v2\/posts\/7865\/revisions"}],"predecessor-version":[{"id":7866,"href":"https:\/\/organizzazione.cai.it\/gr-toscana\/wp-json\/wp\/v2\/posts\/7865\/revisions\/7866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/gr-toscana\/wp-json\/wp\/v2\/media\/36"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/gr-toscana\/wp-json\/wp\/v2\/media?parent=7865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/gr-toscana\/wp-json\/wp\/v2\/categories?post=7865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/gr-toscana\/wp-json\/wp\/v2\/tags?post=7865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}