{"id":1389,"date":"2025-04-05T17:38:52","date_gmt":"2025-04-05T17:38:52","guid":{"rendered":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/?p=1389"},"modified":"2025-04-06T15:49:00","modified_gmt":"2025-04-06T15:49:00","slug":"giornata-operativa-della-sec-calabria-al-parco-della-biodiversita-mediterranea-di-catanzaro","status":"publish","type":"post","link":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/2025\/04\/giornata-operativa-della-sec-calabria-al-parco-della-biodiversita-mediterranea-di-catanzaro\/","title":{"rendered":"Giornata formativa della SEC Calabria al Parco della Biodiversit\u00e0 Mediterranea di Catanzaro"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Sabato 5 aprile 2025 presso il <strong>Parco della Biodiversit\u00e0 Mediterranea di Catanzaro <\/strong>si \u00e8 svolto il primo incontro regionale formativo dedicato alla <strong>progettazione, rilevazione e validazione dei sentieri<\/strong> a cui hanno partecipato i rappresentanti delle cinque Sezioni calabresi di Catanzaro, Cosenza, Castrovillari, Reggio Calabria e Verbicaro della <strong>Struttura Sentieri e Cartografia Calabria (SEC Calabria)<\/strong>, il referente nazionale <em>Emanuele Pisarra<\/em>, il presidente della SEC Calabria <em>Marco Garcea <\/em>e il presidente del Gruppo Regionale Cai Calabria <em>Giuseppe Greco.<\/em><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>La SEC CALABRIA<\/strong> rappresenta un passo significativo nel potenziamento delle <strong>attivit\u00e0 sentieristiche e cartografiche della Calabria<\/strong>, fungendo da prolungamento territoriale della <strong>SOSEC (Struttura Operativa Sentieri e Cartografia) del Club Alpino Italiano.<\/strong> Con l\u2019obiettivo di coordinare, formare e indirizzare le iniziative legate ai sentieri nel contesto regionale, la <strong>SEC CALABRIA <\/strong>si configura come uno strumento essenziale per la valorizzazione del <strong>patrimonio escursionistico calabrese<\/strong> attraverso il <strong>Catasto digitale dei Sentieri. &nbsp;<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Adottare standard nazionali<\/strong> nella gestione della sentieristica rappresenta un passo importante verso la qualit\u00e0 e la <strong>sicurezza dei percorsi escursionistici<\/strong> ed evidenzia anche la necessit\u00e0 di operatori preparati che possano garantire un\u2019adeguata numerazione e catalogazione dei sentieri. In questo contesto, la <strong>creazione e il mantenimento del Catasto Regionale dei Sentier<\/strong>i assume una rilevanza fondamentale. Il <strong>Catasto digitale dei Sentieri <\/strong> non \u00e8 solo un archivio, ma un vero e proprio strumento di coordinamento, evitando confusioni e garantendo una chiara attribuzione delle numerazioni per i nuovi sentieri che verranno realizzati.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">La giornata \u00e8 iniziata con l&#8217;accoglienza dei partecipanti, tutti motivati e pronti a condividere le proprie esperienze. I relatori hanno illustrato le tecniche innovative per la <strong>mappatura dei sentieri<\/strong> mentre i partecipanti hanno avuto l&#8217;opportunit\u00e0 di cimentarsi in attivit\u00e0 pratiche, trasformando le nozioni teoriche in abilit\u00e0 concrete.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Ogni sentiero<\/strong> rappresenta non solo un itinerario naturalistico, ma anche un\u2019occasione per valorizzare la <strong>bellezza del territorio calabrese <\/strong>e incentivare una <strong>fruizione sostenibile del patrimonio ambientale.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"has-medium-font-size\">L\u2019incontro ha favorito un forte spirito di collaborazione e impegno condiviso, con l\u2019obiettivo principale di <strong>migliorare la rete escursionistica della Calabria<\/strong>. Per il <strong>CAI <\/strong>\u00e8 essenziale valorizzare il contributo dei suoi manutentori, e a tal fine sono stati distribuiti i <strong><em>gilet di \u201cmanutentore dei sentieri\u201d, <\/em><\/strong>simbolo del loro indispensabile impegno. Prossimo appuntamento a <strong>Maggio per la seconda giornata formativa<\/strong>.<\/p>\n\n\n\n<p>Hanno partecipato:<\/p>\n\n\n\n<p>Per la Sezione Cai Catanzaro: <em>Piergiorgio IANNACCARO (Presidente Cai Catanzaro) Francesco COLAO, Larissa VOTANO, Valerio PERRI, Marco GARCEA (Presidente SEC Calabria);<\/em><\/p>\n\n\n\n<p>per la Sezione Cai Cosenza: <em>Luigi PATITUCCI, Gianstefano VERRINA e Luigi ZACCARO;<\/em><\/p>\n\n\n\n<p>per la Sezione di Castrovillari: <em>Mariarosaria D\u2019ATRI, Emanuele PISARRA (referente nazionale SOSEC)<\/em><\/p>\n\n\n\n<p>per la Sezione di Reggio Calabria: <em>Consolato DATTOLA;<\/em><\/p>\n\n\n\n<p>per la Sezione di Verbicaro: <em>Carmine CIRIMELE, Ennio BENVENUTO; Giuseppe Andrea COSENTINO, Giuseppe Greco (Presidente GR Cai Calabria)<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1080\" src=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-183340-1440x1080.webp\" alt=\"- CAI\" class=\"wp-image-1390\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-183340-1440x1080.webp 1440w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-183340-960x720.webp 960w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-183340-768x576.webp 768w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-183340-1536x1152.webp 1536w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-183340.webp 1600w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1599\" height=\"899\" src=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-175838-1.webp\" alt=\"- CAI\" class=\"wp-image-1391\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-175838-1.webp 1599w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-175838-1-1280x720.webp 1280w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-175838-1-768x432.webp 768w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-175838-1-1536x864.webp 1536w\" sizes=\"(max-width: 1599px) 100vw, 1599px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1439\" height=\"1080\" src=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-175838-1439x1080.webp\" alt=\"- CAI\" class=\"wp-image-1392\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-175838-1439x1080.webp 1439w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-175838-959x720.webp 959w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-175838-768x576.webp 768w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-175838-1536x1153.webp 1536w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-175838.webp 1599w\" sizes=\"(max-width: 1439px) 100vw, 1439px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1435\" height=\"1080\" src=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190734-1435x1080.webp\" alt=\"- CAI\" class=\"wp-image-1393\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190734-1435x1080.webp 1435w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190734-957x720.webp 957w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190734-768x578.webp 768w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190734-1536x1156.webp 1536w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190734.webp 1600w\" sizes=\"(max-width: 1435px) 100vw, 1435px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1435\" height=\"1080\" src=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190744-1435x1080.webp\" alt=\"- CAI\" class=\"wp-image-1394\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190744-1435x1080.webp 1435w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190744-957x720.webp 957w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190744-768x578.webp 768w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190744-1536x1156.webp 1536w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190744.webp 1600w\" sizes=\"(max-width: 1435px) 100vw, 1435px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1435\" height=\"1080\" src=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190734-1-1435x1080.webp\" alt=\"- CAI\" class=\"wp-image-1395\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190734-1-1435x1080.webp 1435w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190734-1-957x720.webp 957w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190734-1-768x578.webp 768w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190734-1-1536x1156.webp 1536w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/04\/whatsapp-image-2025-04-05-at-190734-1.webp 1600w\" sizes=\"(max-width: 1435px) 100vw, 1435px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"578\" height=\"178\" src=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/03\/logo-sec-calabria-1.webp\" alt=\"- CAI\" class=\"wp-image-1060\" title=\"\"><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 5 aprile 2025 presso il Parco della Biodiversit\u00e0 Mediterranea di Catanzaro si \u00e8 svolto il primo incontro regionale formativo dedicato alla progettazione, rilevazione e validazione dei sentieri a cui [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1390,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/posts\/1389"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/comments?post=1389"}],"version-history":[{"count":12,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/posts\/1389\/revisions"}],"predecessor-version":[{"id":1443,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/posts\/1389\/revisions\/1443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/media\/1390"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/media?parent=1389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/categories?post=1389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/tags?post=1389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}