{"id":3204,"date":"2025-09-22T10:00:42","date_gmt":"2025-09-22T10:00:42","guid":{"rendered":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/?p=3204"},"modified":"2025-09-22T10:04:18","modified_gmt":"2025-09-22T10:04:18","slug":"escursione-al-villaggio-fratta-parco-nazionale-sila","status":"publish","type":"post","link":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/2025\/09\/escursione-al-villaggio-fratta-parco-nazionale-sila\/","title":{"rendered":"Escursione al Villaggio Fratta &#8211; Parco Nazionale Sila"},"content":{"rendered":"\n<p>Domenica 21 settembre si \u00e8 svolta un\u2019escursione nel Parco Nazionale della Sila, attorno al Villaggio Fratta. La partenza \u00e8 avvenuta dall\u2019Ostello di Fratta, dirigendoci verso Pennino della Serra, un tempo conosciuto come &#8220;Jumara du Pinitu&#8221;.<\/p>\n\n\n\n<p>A Pennino della Serra sorgeva la Segheria Serravalle, edificata nel 1870 e operativa fino al 1958. In questa struttura, i tronchi venivano lavorati per ottenere legname, che poi veniva trasportato a valle servendosi di muli e cavalli, testimonianza di un passato in cui il lavoro e la natura erano strettamente connessi.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Successivamente, ci siamo diretti verso la localit\u00e0 Ritorta, dove si trovano alcune baracche utilizzate dagli allevatori. Questo luogo \u00e8 stata occasione per una piacevole pausa: grazie alla generosa ospitalit\u00e0 dell\u2019associazione Villaggio Fratta, abbiamo potuto gustare salumi e formaggi tipici della zona, un\u2019esperienza che ha permesso di immergersi nei sapori autentici della nostra terra.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Il cammino \u00e8 poi proseguito lungo il sentiero CAI 314, che conduce a Macchia del Barone, passando dal &#8220;percorso dei funghi&#8221;, un itinerario didattico curato dall\u2019associazione Villaggio Fratta. Questo tratto ha consentito agli appassionati di funghi ed escursionisti di approfondire la conoscenza della flora e fauna locale e di scoprire l\u2019importanza dei funghi nell\u2019equilibrio dell\u2019ecosistema.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Una giornata immersa nella natura, alla scoperta della storia e dei sapori genuini, organizzata con passione e professionalit\u00e0 dagli accompagnatori e dal team dell\u2019Associazione Villaggio Fratta.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"1080\" data-id=\"3205\" src=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192557-810x1080.webp\" alt=\"- CAI\" class=\"wp-image-3205\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192557-810x1080.webp 810w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192557-540x720.webp 540w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192557-768x1024.webp 768w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192557-1152x1536.webp 1152w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192557.webp 1200w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1080\" data-id=\"3208\" src=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192809-1440x1080.webp\" alt=\"- CAI\" class=\"wp-image-3208\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192809-1440x1080.webp 1440w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192809-960x720.webp 960w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192809-768x576.webp 768w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192809-1536x1152.webp 1536w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192809.webp 2048w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"1080\" data-id=\"3206\" src=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192810-810x1080.webp\" alt=\"- CAI\" class=\"wp-image-3206\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192810-810x1080.webp 810w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192810-540x720.webp 540w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192810-768x1024.webp 768w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192810-1152x1536.webp 1152w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192810.webp 1536w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"1080\" data-id=\"3207\" src=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192934-810x1080.webp\" alt=\"- CAI\" class=\"wp-image-3207\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192934-810x1080.webp 810w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192934-540x720.webp 540w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192934-768x1024.webp 768w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192934-1152x1536.webp 1152w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192934.webp 1200w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1224\" height=\"637\" src=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192627.webp\" alt=\"- CAI\" class=\"wp-image-3209\" style=\"width:670px\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192627.webp 1224w, https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-content\/uploads\/sites\/116\/2025\/09\/whatsapp-image-2025-09-21-at-192627-768x400.webp 768w\" sizes=\"(max-width: 1224px) 100vw, 1224px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 21 settembre si \u00e8 svolta un\u2019escursione nel Parco Nazionale della Sila, attorno al Villaggio Fratta. La partenza \u00e8 avvenuta dall\u2019Ostello di Fratta, dirigendoci verso Pennino della Serra, un tempo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3208,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/posts\/3204"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/comments?post=3204"}],"version-history":[{"count":3,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/posts\/3204\/revisions"}],"predecessor-version":[{"id":3214,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/posts\/3204\/revisions\/3214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/media\/3208"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/media?parent=3204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/categories?post=3204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-catanzaro\/wp-json\/wp\/v2\/tags?post=3204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}