{"id":376,"date":"2024-04-06T20:00:56","date_gmt":"2024-04-06T20:00:56","guid":{"rendered":"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/evento\/escursione-sociale-domenica-14-aprile-2024\/"},"modified":"2024-10-21T05:52:24","modified_gmt":"2024-10-21T05:52:24","slug":"escursione-sociale-domenica-14-aprile-2024","status":"publish","type":"tribe_events","link":"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/evento\/escursione-sociale-domenica-14-aprile-2024\/","title":{"rendered":"Escursione Sociale Domenica 14 Aprile 2024"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-926\" src=\"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-content\/uploads\/sites\/52\/2024\/04\/2bdom14aprile024-scaled-1-960x720.webp\" alt=\"- CAI\" width=\"960\" height=\"720\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-content\/uploads\/sites\/52\/2024\/04\/2bdom14aprile024-scaled-1-960x720.webp 960w, https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-content\/uploads\/sites\/52\/2024\/04\/2bdom14aprile024-scaled-1-1440x1080.webp 1440w, https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-content\/uploads\/sites\/52\/2024\/04\/2bdom14aprile024-scaled-1-768x576.webp 768w, https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-content\/uploads\/sites\/52\/2024\/04\/2bdom14aprile024-scaled-1-1536x1152.webp 1536w, https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-content\/uploads\/sites\/52\/2024\/04\/2bdom14aprile024-scaled-1-2048x1536.webp 2048w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p><strong>CAL\u00c0 DEL SASSO \u2013 SENTIERO DEI 4444 SCALINI <\/strong><\/p>\n<p><strong>VAL BRENTA (VI)<\/strong><\/p>\n<p><strong>Accompagnatori: <\/strong>Gianni Zorzan, Tiziano Pivato, Giovanni De Sario, Massimiliano Bergamo (ASE)<\/p>\n<p><strong>\u00a0<\/strong><strong>\u00a0<\/strong>Riproponiamo l\u2019escursione del 2023 annullata per maltempo<\/p>\n<p><strong>\u00a0<\/strong><em>\u00abQuattromilaquattrocentoquarantaquattro gradini partono dalla Val Brenta, all\u2019altezza di un paese chiamato Valstagna. Si chiama Cal\u00e0 del Sasso, ed \u00e8 una delle opere pi\u00f9 fantastiche delle Alpi\u00bb.<\/em> Il giornalista e scrittore Paolo Rumiz descrive cos\u00ec la scalinata che collega il Comune di Valstagna, nel Canale di Brenta, alla frazione Sasso, di Asiago, nell\u2019Altopiano dei Sette Comuni. La straordinaria architettura venne realizzata alla fine del XIV secolo per trasportare (\u00abcal\u00e0\u00bb letteralmente vuol dir \u201ccalare\u201d, \u201cfar scendere\u201d) il legname da Asiago al fiume Brenta. Un percorso unico nel suo genere, probabilmente la scalinata pi\u00f9 grande d\u2019Italia e forse anche una delle pi\u00f9 lunghe al mondo.<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong>Tipologia del percorso: <\/strong>ad anello<\/p>\n<p><strong>Interesse: <\/strong>naturalistico e storico<\/p>\n<p><strong>Dislivello<\/strong>: +750 mt -750 mt<\/p>\n<p><strong>Difficolt\u00e0: <\/strong>E<\/p>\n<p><strong>Cartina<\/strong>: n. 50 &#8211; Altopiano dei Sette Comuni \u2013 Asiago &#8211; Ortigara<\/p>\n<p><strong>Equipaggiamento<\/strong>: convenzionale per escursionismo<\/p>\n<p><strong>Trasporto<\/strong>: con mezzi propri<\/p>\n<p><strong>Iscrizioni: <\/strong>entro gioved\u00ec 11 aprile<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><a href=\"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-content\/uploads\/sites\/52\/2024\/10\/2.Dom14Aprile024.pdf\" target=\"_blank\" rel=\"noopener\">2.Dom14Aprile024<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAL\u00c0 DEL SASSO \u2013 SENTIERO DEI 4444 SCALINI VAL BRENTA (VI) Accompagnatori: Gianni Zorzan, Tiziano Pivato, Giovanni De Sario, Massimiliano Bergamo (ASE) \u00a0\u00a0Riproponiamo l\u2019escursione del 2023 annullata per maltempo \u00a0\u00abQuattromilaquattrocentoquarantaquattro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":377,"comment_status":"closed","ping_status":"open","template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-json\/wp\/v2\/tribe_events\/376"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-json\/wp\/v2\/comments?post=376"}],"version-history":[{"count":2,"href":"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-json\/wp\/v2\/tribe_events\/376\/revisions"}],"predecessor-version":[{"id":927,"href":"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-json\/wp\/v2\/tribe_events\/376\/revisions\/927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-json\/wp\/v2\/media\/377"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-json\/wp\/v2\/media?parent=376"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-json\/wp\/v2\/tags?post=376"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-s-dona-di-piave\/wp-json\/wp\/v2\/tribe_events_cat?post=376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}