{"id":524,"date":"2021-04-14T20:50:16","date_gmt":"2021-04-14T20:50:16","guid":{"rendered":"https:\/\/organizzazione.cai.it\/sez-siena\/sentieri\/montagnola\/113-115-116-117-118\/"},"modified":"2025-05-28T08:19:17","modified_gmt":"2025-05-28T08:19:17","slug":"113-115-116-117-118","status":"publish","type":"page","link":"https:\/\/organizzazione.cai.it\/sez-siena\/sentieri\/montagnola\/113-115-116-117-118\/","title":{"rendered":"113\/115\/116\/117\/118 &#8211; I Sentieri Del Bosco Di Lecceto"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\"><b>SENTIERO n\u00b0 113: Volte Basse \u2013 Toiano \u2013 Caldana \u2013 S. Colomba \u2013 Fungaia<\/b><\/span><\/p>\n<p class=\"p1\">Dislivelli: salita m 265, discesa m 75<br \/>\nTempo di percorrenza: ore 2<\/p>\n<p class=\"p1\">Poco fuori dall\u2019abitato delle Volte Basse (m 223), alla fine del primo filare di pini che costeggia la Strada Provinciale per Sovicille, si stacca sulla destra, presso un grande cipresso, una stradina sterrata (indicazione per Casa Rossa). Da questo punto prende avvio sia il sentiero n\u00b0 115 (che sale a destra), che il sentiero n\u00b0 113 (che procede in piano nel campo). S\u2019imbocca dunque quest\u2019ultimo che, dopo il campo, si snoda sul limite del bosco di lecci, con percorso parallelo alla strada per Sovicille (ad una distanza da questa di 100-150 metri). Dopo 10 minuti si sbuca su una strada sterrata fiancheggiata da un alto muro in pietra, che va seguita verso destra. Questa procede in piano lungo il bordo di una vigna (ampio panorama sulla Montagnola e sulle colline della Val di Merse), supera il Palazzaccio (torre medievale) e transita davanti alla Villa di Toiano. Dopo il piccolo borgo, ad un bivio si volge a destra e si segue la stradina asfaltata che, con lievi saliscendi, transita per le case di Valli, oltrepassa la deviazione del sentiero n\u00b0 118 (a destra) e giunge all\u2019abitato sparso di Caldana (mezz\u2019ora dalle Volte Basse). Quando la strada compie una brusca svolta a sinistra, la si abbandona per seguire una carrareccia che passa al disotto degli ultimi edifici ed entra nel bosco. Con andamento pianeggiante e con bella visuale ad Ovest sulla Montagnola, questa conduce in 10 minuti al podere Ripostena (prima dell\u2019edificio si stacca a sinistra il sentiero n\u00b0 110). Invece di salire al podere, si deve imboccare un sentiero sulla sinistra che prosegue in piano nel bosco di cerri, costeggiando per un lungo tratto la sponda destra del Fosso Arnano. Dopo altri 15 minuti di cammino, si sbuca su una stradella proveniente dal campo sottostante: si scende al campo (sinistra) e si va a percorrere, lungamente, il suo bordo destro, gi\u00e0 in vista della imponente villa di S. Colomba. Il sentiero esce infine sulla strada di accesso al podere Pastine di Sotto (inizio a destra del sentiero n\u00b0 116). Si va a sinistra, seguendo la carrozzabile che procede in piano nel bosco, s\u2019ignora una deviazione a sinistra e si continua lungo il bordo dei campi, fino a sbucare sulla strada asfaltata che dal Pian del Lago sale a Celsa. Si segue l\u2019asfalto verso sinistra per circa 100 metri, quindi s\u2019imbocca a destra una mulattiera che sale attraverso i campi, costeggiata da alberi e da vecchi muri. Giunti ad un bivio con un grosso cipresso, si volge a destra e si arriva in breve a S. Colomba (m 338, un\u2019ora da Caldana \u2013 ore 1,30 totali). Dalla Villa Petrucci inizia il sentiero n\u00b0 108, mentre il n\u00b0 113 prosegue a destra, in discesa, lungo la strada asfaltata. Percorsi circa 200 metri, si abbandona l\u2019asfalto per immettersi sulla strada sterrata che si stacca a sinistra (indicazioni per Altichiari e Cannuccio). Attraversato un campo ed un breve tratto di bosco, si giunge ad un bivio dove si svolta a destra, verso Altichiari (la strada principale prosegue diritto e conduce a Cannuccio). Dopo la Casa Altichiari, circondata da oliveti, si percorre un sentiero affiancato a sinistra da un muro a secco. Entrati nel bosco, poco dopo si giunge ad un bivio, dove si prende il ramo di destra che cala in una valletta. Risalito l\u2019opposto versante della valle con percorso assai ripido e sassoso, la mulattiera passa a sinistra del podere Casagatti, interseca una strada (continuare diritto) e, dopo un ultimo tratto in mezzo a due muretti, termina alle case di Fungaia (m 395, mezz\u2019ora da S. Colomba \u2013 ore 2 totali). Qui transita il sentiero n\u00b0 106 che dal Pian del Lago sale a Casa Alteri.<br \/>\n<b><\/b><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Luoghi d\u2019interesse storico lungo il sentiero n\u00b0 113<\/b><\/span><br \/>\n<b>Palazzaccio<\/b><br \/>\nIl Palazzaccio viene citato per la prima volta in un documento del 1216 come fortilizio della Repubblica di Siena. Nel 1333 il borgo fu messo a ferro e fuoco dalle truppe pisane, insieme al castello di Sovicille ed alla Pieve di Ponte allo Spino. Nel complesso si notano molte tracce di finestre ad arco. La parte pi\u00f9 bella \u00e8 il cortile, con un alto pilastro quadrato che sorregge quattro volte a crociera.<br \/>\n<b>S.Colomba<\/b><br \/>\nVedi luoghi d\u2019interesse storico lungo il sentiero n\u00b0 108.<\/p>\n<p><span class=\"s1\"><b>SENTIERO n\u00b0 115: Volte Basse \u2013 Sentiero n\u00b0 118<\/b><\/span><\/p>\n<p>Dislivelli: salita m 120, discesa m 0<br \/>\nTempo di percorrenza: ore 0,30<\/p>\n<p>Poco fuori dall\u2019abitato delle Volte Basse (m 223), alla fine del primo filare di pini che costeggia la strada Provinciale per Sovicille, s\u2019imbocca sulla destra, presso un grande cipresso, la stradina sterrata che sale verso \u201cCasa Rossa\u201d (dallo stesso punto prende avvio a sinistra anche il sentiero n\u00b0 113, che procede in piano nel campo). Oltrepassata la vicina \u201cCasa Rossa\u201d, la strada bianca si trasforma in strada di bosco acciottolata e disconnessa e segue in principio la recinzione della suddetta propriet\u00e0. Procedendo in leggera e costante salita nel lecceto, si giunge ad un bivio in prossimit\u00e0 di un grande leccio, dove bisogna volgere a destra. Da qui in poi il sentiero si restringe (restando comunque sempre ben evidente) e la salita si fa pi\u00f9 agevole. Toccata la quota massima di 325 m, il tracciato prosegue in piano, in ambiente pi\u00f9 aperto e soleggiato. Dopo circa 500 metri, s\u2019incontra una stradina che va seguita verso sinistra, per poche decine di metri, fino a quando quest\u2019ultima s\u2019immette nel percorso n\u00b0 118.<\/p>\n<p><span class=\"s1\"><b>SENTIERO n\u00b0 116: Pastine di Sotto \u2013 S. Leonardo al Lago \u2013 Galleria del Granduca<\/b><\/span><\/p>\n<p>Dislivelli: salita m 45, discesa m 90<br \/>\nTempo di percorrenza: ore 2,15<\/p>\n<p>Il sentiero n\u00b0 116 si stacca dal sentiero n\u00b0 113 (che da Caldana conduce a S. Colomba) presso una radura con quattro grandi querce, poco sotto il podere Pastine di Sotto. Si segue la carrareccia che sale in breve alla suddetta casa colonica, aggirandola sulla destra. Dopo l\u2019edificio si continua per una stradina di bosco dal fondo assai disconnesso, che procede in lieve salita. Pi\u00f9 in alto questa s\u2019immette in una strada bianca che va seguita verso destra, in direzione di Bellaria. Dopo l\u2019ultima casa di Pastine di Sopra (m 350), in prossimit\u00e0 di un bel cipresso solitario emergente da un gruppo di lecci si devia a sinistra, imboccando una mulattiera: questa scende per il lecceto, costeggiata all\u2019inizio da un vecchio muro a secco. Oltrepassata un\u2019abitazione (destra), si giunge all\u2019Eremo di S. Leonardo al Lago (m 292), che va aggirato sulla sinistra, raggiungendo cos\u00ec la parte posteriore del complesso. Qui prende avvio a destra il sentiero n\u00b0 117 che porta alla Strada del Ferratore. Il sentiero n\u00b0 116 prosegue invece diritto, in direzione Nord-Est, ed esce ben presto sulla strada bianca presso la localit\u00e0 Osteriaccia. Qui si deve imboccare un sentiero che ha inizio sull\u2019altro lato della strada, poco a destra dell\u2019edificio. Si passa subito a monte dell\u2019Inghiottitoio del Mulinaccio e, attraversato il bosco di cerri, si esce infine nei campi del Pian del Lago, a breve distanza dall\u2019obelisco denominato \u201cGuglia\u201d, fatto erigere dal Granduca Leopoldo di Lorena. Dietro la stele ha inizio la galleria di bonifica del Pian del Lago, detta \u201cGalleria del Granduca\u201d. Si scende dunque nel canale e, muniti di torcia elettrica e stivali di gomma, si va a percorrere i 2173 metri di galleria (attenzione: dopo periodi molto piovosi la traversata non \u00e8 effettuabile). All\u2019uscita del tunnel si guada il Torrente Rigo e si sbuca sulla Strada Provinciale del Ferratore (Volte Basse \u2013 Pian del Lago). Il tempo di percorrenza di questo itinerario \u00e8 leggermente pi\u00f9 alto della media, dato che per l\u2019attraversamento del Canale del Granduca occorre un\u2019ora abbondante. Volendo tornare a piedi a S. Leonardo al Lago, \u00e8 consigliabile seguire il sentiero n\u00b0 117, che inizia dalla Strada del Ferratore, a breve distanza dal punto in cui termina il sentiero n\u00b0 116 (in sostanza, usciti sulla strada bisogna dirigersi verso destra \u2013 Nord).<br \/>\n<b><\/b><\/p>\n<p><span class=\"s1\"><b>Luoghi di interesse storico lungo il sentiero n\u00b0 116<\/b><\/span><br \/>\n<b>S.Leonardo al Lago<\/b><br \/>\nL\u2019eremo Agostiniano di S. Leonardo al Lago \u00e8 circondato da boschi, motivo per cui un tempo veniva chiamato \u201dEremo di Selva del Lago\u201d. Incerta la data della fondazione, ma da antichi documenti sappiamo che doveva gi\u00e0 esistere nel 1112. Nel 1366 il monastero fu fortificato per offrire rifugio alla popolazione di S. Colomba in caso di guerre. L\u2019Eremo fu soppresso nel 1782 ed incorporato all\u2019Eremo di Lecceto. Nella cappella dietro l\u2019altare si possono osservare alcuni interessanti affreschi di Lippo Vanni rappresentanti scene dalla vita di Maria, mentre nell\u2019ex Sala Capitolare (a cui si accede dal chiostro interno) si trovano i resti di un affresco di Giovanni di Paolo rappresentante una Crocifissione.<br \/>\n<b>Galleria del Granduca o Guglia<\/b><br \/>\nLa Galleria del Granduca, lunga 2173 metri, fu costruita nel 1770 per prosciugare le acque del Pian del Lago che allora stagnavano per 156 ettari circa e per un\u2019altezza, all\u2019estremit\u00e0 Sud, di oltre tre metri. L\u2019opera fu realizzata in gran parte da Francesco Bindi Sergardi e fu solo perfezionata dal Granduca Leopoldo di Lorena. Le caratteristiche principali sono la costruzione in mattoni con \u201cvolta a botte\u201d e la pavimentazione in pietra serena con pendenza del 2 per mille. Prese il nome di Guglia da una stele posta all\u2019imbocco del canale, con tanto di iscrizione a gloria del Granduca.<\/p>\n<p><span class=\"s1\"><b>SENTIERO n\u00b0 117: Valle del Rigo \u2013 S. Leonardo al Lago<\/b><\/span><\/p>\n<p>Dislivelli: salita m 80, discesa m 50<br \/>\nTempo di percorrenza: ore 0,50<\/p>\n<p>Il sentiero n\u00b0 117 inizia dalla valle del Torrente Rigo, sul lato Ovest della Strada Provinciale del Ferratore, a breve distanza dallo sbocco della Galleria del Granduca (sentiero n\u00b0 116). Il tracciato inizia subito a salire in mezzo ad una fitta boscaglia, fino ad immettersi in una stradina di bosco che va seguita verso destra. Dopo trecento metri circa, si attraversa lo stradone dell\u2019acquedotto e, giunti all\u2019altezza di un grande leccio (localit\u00e0 Piazza ai Lecci), s\u2019incontra sulla sinistra l\u2019innesto del sentiero n\u00b0 118 proveniente da Valli (da questo punto, seguendo quest\u2019ultimo, si pu\u00f2 fare una visita all\u2019Eremo di Lecceto \u2013 30 minuti a\/r). Dopo pochi metri ci si trova di fronte ad un cipresso solitario: qui si abbandona la stradina e si segue sulla destra un piccolo ma ben evidente sentiero che s\u2019inoltra nel fitto bosco di lecci e corbezzoli, con direzione Ovest-Nord-Ovest. Si pu\u00f2 notare che questo tratto di sentiero ha il fondo molto battuto dal passaggio di animali selvatici: infatti il terreno \u00e8 sgombro da vegetazione, mentre nella parte alta i rami dei corbezzoli quasi s\u2019intrecciano. Dopo circa un chilometro si scende ad un quadrivio, dove si prosegue diritto. Subito dopo s\u2019incontra un altro quadrivio: anche qui si va diritto, tralasciando le mulattiere di destra e di sinistra. Bisogna per\u00f2 fare molta attenzione, in quanto, percorsi pochi metri, occorre imboccare un sentierino sulla sinistra, che s\u2019inoltra nel fitto bosco. Questo ci condurr\u00e0 in breve nei pressi dell\u2019Eremo di S. Leonardo al Lago, dove il nostro sentiero n\u00b0 117 s\u2019inserisce nel sentiero n\u00b0 116.<\/p>\n<p><span class=\"s1\"><b>Luoghi di interesse storico lungo il sentiero n\u00b0 117<\/b><\/span><br \/>\n<b>S.Leonardo al Lago<\/b><br \/>\nVedi luoghi d\u2019interesse storico lungo il sentiero n\u00b0 116.<\/p>\n<p><span class=\"s1\"><b>SENTIERO n\u00b0 118: Valli \u2013 Lecceto \u2013 Sentiero n\u00b0 117<\/b><\/span><\/p>\n<p>Dislivelli: salita m 205, discesa m 95<br \/>\nTempo di percorrenza: ore 1,15<\/p>\n<p>Il sentiero n\u00b0 118 inizia poco oltre le case di Valli, sul lato destro della strada (procedendo in direzione Caldana). Da Valli transita il percorso n\u00b0 113. Un bel sentiero di bosco, stretto e a volte un po\u2019 infrascato, ma ben battuto ed evidente, affronta subito la salita al Poggio Cannicci (m 414), il punto pi\u00f9 alto del Bosco di Lecceto. Durante la salita si consiglia ogni tanto di voltarsi per ammirare la bella veduta sulla valle sottostante, con i gruppi di case di Caldana e di Ponte allo Spino; pi\u00f9 in alto si possono osservare Sovicille, Tegoia, Romitorio e il campanile di Pernina. Arrivati al culmine, il sentiero procede per un centinaio di metri in piano, fino a sbucare su una stradina di bosco. Proprio sull\u2019incrocio, si pu\u00f2 notare uno stagno circondato da querce: \u00e8 questo l\u2019unico luogo in tutto il Bosco di Lecceto dove gli animali possono trovare un po\u2019 d\u2019acqua anche in estate. Da qui si segue per pochi metri la stradina verso destra, poi s\u2019imbocca a sinistra un sentierino che all\u2019inizio procede in piano, quindi in leggera discesa, con belle vedute sull\u2019Eremo di Lecceto (verso Est) e sulla lontana Val d\u2019Arbia (verso Sud-Est). Alla fine della discesa, presso l\u2019ingresso del Centro Ippico \u201cIl Cannuccio\u201d (sinistra), la mulattiera sbuca su una strada bianca, che va seguita verso sinistra (direzione Lecceto). Si oltrepassa subito l\u2019innesto del sentiero n\u00b0 115 (destra) e, poco pi\u00f9 avanti, s\u2019incontra una grande area attrezzata (posta sulla destra della strada) con sedili in pietra e grande griglia, molto utile per fare una piacevole sosta, magari all\u2019ora di pranzo. Il nostro itinerario prosegue sulla carrozzabile per circa 100 metri, quindi volge a sinistra, sulla strada per la Loccaia. Da questo punto \u00e8 consigliabile una visita all\u2019Eremo di Lecceto, raggiungibile in pochi minuti. Lasciata quasi subito la strada per la Loccaia, si prosegue diritto, in direzione Nord, costeggiando la recinzione dell\u2019Eremo di Lecceto. Si scende fino a trovare lo stradone dell\u2019acquedotto, lo si segue verso destra per una cinquantina di metri e, giunti nei pressi di un grande tombino d\u2019ispezione si devia a sinistra salendo fino a Piazza ai Lecci, dove il sentiero n\u00b0 118 s\u2019innesta nel sentiero n\u00b0 117 (Strada del Ferratore \u2013 S. Leonardo al Lago).<br \/>\n<b><\/b><\/p>\n<p><span class=\"s1\"><b>Luoghi d\u2019interesse storico lungo il sentiero n\u00b0 118<\/b><\/span><br \/>\n<b>Eremo di Lecceto<\/b><br \/>\nEremo Agostiniano del quale risalta un torrione quadrato con base a scarpa, munito di arciere e coronato di archetti a mattoni con piombatoi su mensole di pietra. La chiesa \u00e8 stata rimaneggiata in epoca barocca. All\u2019interno dell\u2019eremo vi sono due chiostri, nel pi\u00f9 antico dei quali sono presenti un pozzo e degli affreschi del secolo XV.<\/p>\n<p class=\"p2\"><a href=\"https:\/\/organizzazione.cai.it\/sez-siena\/wp-content\/uploads\/sites\/48\/2024\/10\/Traccia-Gps-113-115-116-117-118-1.zip\">Traccia Gpx sentieri 113-115-116-117-118<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SENTIERO n\u00b0 113: Volte Basse \u2013 Toiano \u2013 Caldana \u2013 S. Colomba \u2013 Fungaia Dislivelli: salita m 265, discesa m 75 Tempo di percorrenza: ore 2 Poco fuori dall\u2019abitato delle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36,"parent":501,"menu_order":42,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"rankMath":{"parentDomain":"organizzazione.cai.it","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"L&#039;immagine in evidenza dovrebbe essere di almeno 200 x 200 pixel per essere ripresa da Facebook e altri siti di social media.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"113-115-116-117-118","permalinkFormat":"https:\/\/organizzazione.cai.it\/sez-siena\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":false,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"nome utente","primaryTerm":0,"authorName":"admin","titleTemplate":"%title% %sep% CAI %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":true},"homeUrl":"https:\/\/organizzazione.cai.it\/sez-siena","objectID":524,"objectType":"post","locale":"it","localeFull":"it_IT","overlayImages":{"play":{"name":"Icona di riproduzione","url":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/var\/www\/vhosts\/organizzazione.cai.it\/httpdocs\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Icona GIF","url":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/var\/www\/vhosts\/organizzazione.cai.it\/httpdocs\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-content\/uploads\/sites\/48\/2024\/09\/og.webp","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Forganizzazione.cai.it%2Fsez-siena&r=https%3A%2F%2Forganizzazione.cai.it%2Fsez-siena%2Fwp-json%2Fwp%2Fv2%2Fpages%2F524%3Fnonce%3D627daeff82","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAQCAYAAAAf8\/9hAAABs0lEQVR4AWL4\/\/8\/RRjO8Iucx+noO0MWUDo16FYABMGP6ZfUcRnWtm27jVPbtm3bttuH2t3eFPcY9pLz7NxiLjCyVd87pKnHyqXyxtCs8APd0rnyxiu4qSeA3QEDrAwBDrT1s1Rc\/OrjLZwqVmOSu6+Lamcpp2KKMA9PH1BYXMe1mUP5qotvXTywsOEEYHXxrY+3cqk6TMkYpNr2FeoY3KIr0RPtn9wQ2unlA+GMkRw6+9TFw4YTwDUzx\/JVvARj9KaedXRO8P5B1Du2S32smzqUrcKGEyA+uAgQjKX7zf0boWHGfn71jIKj2689gxp7OAGShNcBUmLMPVjZuiKcA2vuWHHDCQxMCz629kXAIU4ApY15QwggAFbfOP9DhgBJ+nWVJ1AZAfICAj1pAlY6hCADZnveQf7bQIwzVONGJonhLIlS9gr5mFg44Xd+4S3XHoGNPdJl1INIwKyEgHckEhgTe1bGiFY9GSFBYUwLh1IkiJUbY407E7syBSFxKTszEoiE\/YdrgCEayDmtaJwCI9uu8TKMuZSVfSa4BpGgzvomBR\/INhLGzrqDotp01ZR8pn\/1L0JN9d9XNyx0AAAAAElFTkSuQmCC","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Aggiorna","trendsPreviewImage":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-json\/wp\/v2\/pages\/524"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-json\/wp\/v2\/comments?post=524"}],"version-history":[{"count":1,"href":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-json\/wp\/v2\/pages\/524\/revisions"}],"predecessor-version":[{"id":4274,"href":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-json\/wp\/v2\/pages\/524\/revisions\/4274"}],"up":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-json\/wp\/v2\/pages\/501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-json\/wp\/v2\/media\/36"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/sez-siena\/wp-json\/wp\/v2\/media?parent=524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}