{"id":2448,"date":"2025-07-15T19:14:42","date_gmt":"2025-07-15T19:14:42","guid":{"rendered":"https:\/\/organizzazione.cai.it\/sez-villadossola\/?p=2448"},"modified":"2025-07-15T19:14:42","modified_gmt":"2025-07-15T19:14:42","slug":"26-luglio-festa-allalpe-san-giacomo","status":"publish","type":"post","link":"https:\/\/organizzazione.cai.it\/sez-villadossola\/2025\/07\/26-luglio-festa-allalpe-san-giacomo\/","title":{"rendered":"26 luglio Festa all\u2019Alpe San Giacomo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"757\" height=\"1080\" src=\"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/img_4244-757x1080.webp\" alt=\"- CAI\" class=\"wp-image-2449\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/img_4244-757x1080.webp 757w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/img_4244-505x720.webp 505w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/img_4244-768x1095.webp 768w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/img_4244-1077x1536.webp 1077w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/img_4244.webp 1253w\" sizes=\"(max-width: 757px) 100vw, 757px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":145,"featured_media":36,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/posts\/2448"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/users\/145"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/comments?post=2448"}],"version-history":[{"count":1,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/posts\/2448\/revisions"}],"predecessor-version":[{"id":2450,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/posts\/2448\/revisions\/2450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/media\/36"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/media?parent=2448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/categories?post=2448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/tags?post=2448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}