{"id":2571,"date":"2025-07-29T18:01:19","date_gmt":"2025-07-29T18:01:19","guid":{"rendered":"https:\/\/organizzazione.cai.it\/sez-villadossola\/?p=2571"},"modified":"2025-07-29T18:01:19","modified_gmt":"2025-07-29T18:01:19","slug":"foto-lautani-di-seppiana-e-festa-alpe-san-giacomo","status":"publish","type":"post","link":"https:\/\/organizzazione.cai.it\/sez-villadossola\/2025\/07\/foto-lautani-di-seppiana-e-festa-alpe-san-giacomo\/","title":{"rendered":"Foto Lautani di Seppiana e festa alpe San Giacomo"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1080\" data-id=\"2572\" src=\"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/9fb9b2d4-9a26-4fb8-a8cd-caf949512a05-1440x1080.webp\" alt=\"- CAI\" class=\"wp-image-2572\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/9fb9b2d4-9a26-4fb8-a8cd-caf949512a05-1440x1080.webp 1440w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/9fb9b2d4-9a26-4fb8-a8cd-caf949512a05-960x720.webp 960w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/9fb9b2d4-9a26-4fb8-a8cd-caf949512a05-768x576.webp 768w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/9fb9b2d4-9a26-4fb8-a8cd-caf949512a05-1536x1152.webp 1536w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/9fb9b2d4-9a26-4fb8-a8cd-caf949512a05.webp 1600w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1080\" data-id=\"2575\" src=\"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/d358c944-6bc6-4ef9-8439-a5f8cfa9bd39-1440x1080.webp\" alt=\"- CAI\" class=\"wp-image-2575\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/d358c944-6bc6-4ef9-8439-a5f8cfa9bd39-1440x1080.webp 1440w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/d358c944-6bc6-4ef9-8439-a5f8cfa9bd39-960x720.webp 960w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/d358c944-6bc6-4ef9-8439-a5f8cfa9bd39-768x576.webp 768w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/d358c944-6bc6-4ef9-8439-a5f8cfa9bd39-1536x1152.webp 1536w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/d358c944-6bc6-4ef9-8439-a5f8cfa9bd39.webp 1600w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"1080\" data-id=\"2573\" src=\"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/1a653ac0-80d5-43ff-a528-8e59817601cb-810x1080.webp\" alt=\"- CAI\" class=\"wp-image-2573\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/1a653ac0-80d5-43ff-a528-8e59817601cb-810x1080.webp 810w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/1a653ac0-80d5-43ff-a528-8e59817601cb-540x720.webp 540w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/1a653ac0-80d5-43ff-a528-8e59817601cb-768x1024.webp 768w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/1a653ac0-80d5-43ff-a528-8e59817601cb-1152x1536.webp 1152w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/1a653ac0-80d5-43ff-a528-8e59817601cb.webp 1200w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"1080\" data-id=\"2574\" src=\"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/8d95b3f2-d798-4ecc-af7a-dfa976f6ae1c-810x1080.webp\" alt=\"- CAI\" class=\"wp-image-2574\" title=\"\" srcset=\"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/8d95b3f2-d798-4ecc-af7a-dfa976f6ae1c-810x1080.webp 810w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/8d95b3f2-d798-4ecc-af7a-dfa976f6ae1c-540x720.webp 540w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/8d95b3f2-d798-4ecc-af7a-dfa976f6ae1c-768x1024.webp 768w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/8d95b3f2-d798-4ecc-af7a-dfa976f6ae1c-1152x1536.webp 1152w, https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2025\/07\/8d95b3f2-d798-4ecc-af7a-dfa976f6ae1c.webp 1200w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":145,"featured_media":36,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/posts\/2571"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/users\/145"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/comments?post=2571"}],"version-history":[{"count":1,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/posts\/2571\/revisions"}],"predecessor-version":[{"id":2576,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/posts\/2571\/revisions\/2576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/media\/36"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/media?parent=2571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/categories?post=2571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/tags?post=2571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}