{"id":924,"date":"2024-01-31T10:02:21","date_gmt":"2024-01-31T10:02:21","guid":{"rendered":"https:\/\/organizzazione.cai.it\/sez-villadossola\/2024\/01\/gita-a-saronno-monti-sibillini-ottobre-2024\/"},"modified":"2024-01-31T10:02:21","modified_gmt":"2024-01-31T10:02:21","slug":"gita-a-saronno-monti-sibillini-ottobre-2024","status":"publish","type":"post","link":"https:\/\/organizzazione.cai.it\/sez-villadossola\/2024\/01\/gita-a-saronno-monti-sibillini-ottobre-2024\/","title":{"rendered":"Gita A Saronno &#8211; Monti Sibillini &#8211; Ottobre 2024"},"content":{"rendered":"<p><a href=\"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-content\/uploads\/sites\/57\/2024\/10\/PDF_003370.pdf\" target=\"_blank\" rel=\"noopener\">Locandina gita<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Locandina gita<\/p>\n","protected":false},"author":1,"featured_media":36,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/posts\/924"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/comments?post=924"}],"version-history":[{"count":0,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/posts\/924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/media\/36"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/media?parent=924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/categories?post=924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-villadossola\/wp-json\/wp\/v2\/tags?post=924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}