{"id":685,"date":"2025-10-24T11:34:06","date_gmt":"2025-10-24T11:34:06","guid":{"rendered":"https:\/\/organizzazione.cai.it\/sez-volpiano\/?page_id=685"},"modified":"2026-02-26T09:33:05","modified_gmt":"2026-02-26T09:33:05","slug":"videoteca","status":"publish","type":"page","link":"https:\/\/organizzazione.cai.it\/sez-volpiano\/biblio-videoteca\/videoteca\/","title":{"rendered":"Videoteca"},"content":{"rendered":"\n<!DOCTYPE html>\n<html lang=\"it\">\n<head>\n    <meta charset=\"UTF-8\">\n    <meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n    <title>Videoteca CAI VOLPIANO<\/title>\n    <style>\n        #cai-library-wrapper * {\n            box-sizing: border-box;\n        }\n        \n        #cai-library-wrapper {\n            font-family: -apple-system, BlinkMacSystemFont, \"Segoe UI\", Roboto, Oxygen-Sans, Ubuntu, Cantarell, sans-serif;\n            padding: 40px 20px;\n            margin: -20px;\n        }\n\n        #cai-library-wrapper .cai-container {\n            max-width: 1100px;\n            margin: 0 auto;\n        }\n\n        \/* Header *\/\n        #cai-library-wrapper .cai-header {\n            background: white;\n            border-radius: 24px;\n            padding: 40px;\n            margin-bottom: 30px;\n            box-shadow: 0 20px 60px rgba(0, 0, 0, 0.3);\n            text-align: center;\n        }\n\n        #cai-library-wrapper .cai-header h1 {\n            margin: 0;\n            font-size: 32px;\n            color: #2d3748;\n            margin-bottom: 10px;\n            font-weight: 700;\n        }\n\n        #cai-library-wrapper .cai-update-date {\n            color: #718096;\n            font-size: 14px;\n            font-weight: 500;\n            display: inline-block;\n            padding: 6px 16px;\n            background: #f7fafc;\n            border-radius: 20px;\n            margin-top: 8px;\n        }\n\n        #cai-library-wrapper .cai-info-warn {\n            color: #718096;\n            font-size: 14px;\n            font-weight: 500;\n            padding: 6px 16px;\n            background: #f7fafc;\n            border-radius: 20px;\n            margin-top: 8px;\n        }\n\n        #cai-library-wrapper .cai-info-warn ul {\n            text-align: left;\n            margin: 10px 0;\n        }\n\n        \/* Content Section *\/\n        #cai-library-wrapper .cai-content-section {\n            border-radius: 24px;\n            animation: cai-fadeIn 0.4s ease;\n        }\n\n        @keyframes cai-fadeIn {\n            from {\n                opacity: 0;\n                transform: translateY(20px);\n            }\n            to {\n                opacity: 1;\n                transform: translateY(0);\n            }\n        }\n\n        \/* Author Cards *\/\n        #cai-library-wrapper .cai-author-grid {\n            display: grid;\n            grid-template-columns: repeat(auto-fill, minmax(320px, 1fr));\n            gap: 20px;\n            transition: opacity 0.3s ease;\n        }\n\n        #cai-library-wrapper .cai-author-grid.fade-out {\n            opacity: 0;\n        }\n\n        #cai-library-wrapper .cai-author-card {\n            border-radius: 16px;\n            padding: 24px;\n            cursor: pointer;\n            transition: all 0.3s ease;\n            border: 2px solid transparent;\n            position: relative;\n            overflow: hidden;\n            box-shadow: 0 4px 20px rgba(0, 0, 0, 0.1);\n            background: white;\n        }\n\n        #cai-library-wrapper .cai-author-card:hover {\n            transform: translateY(-4px);\n            box-shadow: 0 8px 25px rgba(102, 126, 234, 0.3);\n            border-color: #0e60c6;\n        }\n\n        #cai-library-wrapper .cai-author-card-content {\n            position: relative;\n            z-index: 1;\n        }\n\n        #cai-library-wrapper .cai-author-name {\n            font-size: 18px;\n            font-weight: 600;\n            color: #2d3748;\n            margin-bottom: 12px;\n            display: flex;\n            align-items: center;\n            gap: 10px;\n        }\n\n        #cai-library-wrapper .cai-author-icon {\n            width: 36px;\n            height: 36px;\n            background: linear-gradient(135deg, #0e60c6, #13304a);\n            border-radius: 10px;\n            display: flex;\n            align-items: center;\n            justify-content: center;\n            color: white;\n            font-size: 16px;\n            flex-shrink: 0;\n        }\n\n        #cai-library-wrapper .cai-book-count-badge {\n            display: inline-flex;\n            align-items: center;\n            gap: 8px;\n            background: white;\n            padding: 8px 16px;\n            border-radius: 40px;\n            font-size: 14px;\n            font-weight: 600;\n            color: #0e60c6;\n            box-shadow: 0 2px 8px rgba(0, 0, 0, 0.1);\n        }\n\n        #cai-library-wrapper .cai-book-count-badge .arrow {\n            font-size: 18px;\n            transition: transform 0.3s ease;\n        }\n\n        #cai-library-wrapper .cai-author-card:hover .cai-book-count-badge .arrow {\n            transform: translateX(4px);\n        }\n\n        \/* Modal *\/\n        #cai-library-wrapper .cai-modal {\n            display: none;\n            position: fixed;\n            z-index: 999999;\n            left: 0;\n            top: 0;\n            width: 100%;\n            height: 100%;\n            backdrop-filter: blur(8px);\n            animation: cai-fadeIn 0.3s ease;\n            overflow-y: auto;\n            padding: 40px 0;\n        }\n\n        #cai-library-wrapper .cai-modal-content {\n            background: white;\n            margin: 0 auto;\n            width: 90%;\n            max-width: 700px;\n            border-radius: 24px;\n            box-shadow: 0 25px 50px rgba(0, 0, 0, 0.5);\n            max-height: none;\n            display: flex;\n            flex-direction: column;\n            animation: cai-slideUp 0.4s cubic-bezier(0.4, 0, 0.2, 1);\n            overflow: hidden;\n            position: relative;\n            min-height: min-content;\n        }\n\n        @keyframes cai-slideUp {\n            from {\n                transform: translateY(100px);\n                opacity: 0;\n            }\n            to {\n                transform: translateY(0);\n                opacity: 1;\n            }\n        }\n\n        #cai-library-wrapper .cai-modal-header {\n            padding: 30px 32px;\n            background: linear-gradient(135deg, #0e60c6, #13304a);\n            color: white;\n            display: flex;\n            justify-content: space-between;\n            align-items: center;\n        }\n\n        #cai-library-wrapper .cai-modal-header h2 {\n            margin: 0;\n            font-size: 22px;\n            font-weight: 700;\n            color: white;\n        }\n\n        #cai-library-wrapper .cai-close {\n            color: white;\n            font-size: 32px;\n            font-weight: 300;\n            cursor: pointer;\n            border: none;\n            background: rgba(255, 255, 255, 0.2);\n            padding: 0;\n            width: 40px;\n            height: 40px;\n            display: flex;\n            align-items: baseline;\n            justify-content: space-around;\n            border-radius: 40px;\n            transition: all 0.2s;\n        }\n\n        #cai-library-wrapper .cai-close:hover {\n            background: rgba(255, 255, 255, 0.3);\n            transform: rotate(90deg);\n        }\n\n        #cai-library-wrapper .cai-modal-body {\n            padding: 32px;\n            overflow-y: auto;\n            flex: 1;\n        }\n\n        #cai-library-wrapper .cai-book-list {\n            list-style: none;\n            padding: 0;\n            margin: 0;\n        }\n\n        #cai-library-wrapper .cai-book-item {\n            padding: 18px 20px;\n            margin-bottom: 12px;\n            background: linear-gradient(135deg, #f7fafc 0%, #edf2f7 100%);\n            border-radius: 16px;\n            display: flex;\n            justify-content: space-between;\n            align-items: center;\n            transition: all 0.3s ease;\n            border: 2px solid transparent;\n        }\n\n        #cai-library-wrapper .cai-book-item:hover {\n            background: linear-gradient(135deg, #edf2f7 0%, #e2e8f0 100%);\n            border-color: #cbd5e0;\n            transform: translateX(4px);\n        }\n\n        #cai-library-wrapper .cai-book-title {\n            flex: 1;\n            font-weight: 500;\n            color: #2d3748;\n            font-size: 15px;\n        }\n\n        #cai-library-wrapper .cai-book-number {\n            background: linear-gradient(135deg, #0e60c6, #13304a);\n            color: white;\n            padding: 6px 14px;\n            border-radius: 40px;\n            font-size: 13px;\n            font-weight: 700;\n            min-width: 40px;\n            text-align: center;\n            box-shadow: 0 2px 8px rgba(102, 126, 234, 0.3);\n        }\n\n        #cai-library-wrapper .pagination {\n            display: flex;\n            flex-wrap: wrap;\n            justify-content: center;\n            align-items: center;\n            gap: 10px;\n            margin-top: 40px;\n        }\n\n        #cai-library-wrapper .pagination button {\n            background: white;\n            color: #0e60c6 !important;\n            padding: 10px 18px;\n            cursor: pointer;\n            font-size: 1em;\n            font-weight: 600;\n            transition: all 0.2s;\n        }\n\n        #cai-library-wrapper .pagination button:hover:not(:disabled) {\n            background: #0e60c6;\n            color: white !important;\n            transform: translateY(-2px);\n            box-shadow: 0 4px 12px rgba(52, 152, 219, 0.3);\n        }\n\n        #cai-library-wrapper .pagination button:disabled {\n            opacity: 0.4;\n            cursor: not-allowed;\n        }\n\n        #cai-library-wrapper .pagination button.active {\n            background: #0e60c6;\n            color: white !important;\n        }\n\n        #cai-library-wrapper .pagination .dots {\n            color: #7f8c8d;\n            padding: 0 5px;\n            user-select: none;\n        }\n\n        #cai-library-wrapper .page-info {\n            color: #7f8c8d;\n            font-size: 0.95em;\n            text-align: center;\n            margin-top: 15px;\n        }\n\n        @media (max-width: 768px) {\n            #cai-library-wrapper {\n                padding: 20px 12px;\n            }\n\n            #cai-library-wrapper .cai-header {\n                padding: 30px 24px;\n                border-radius: 20px;\n            }\n\n            #cai-library-wrapper .cai-header h1 {\n                font-size: 24px;\n            }\n\n            #cai-library-wrapper .cai-author-grid {\n                grid-template-columns: 1fr;\n                gap: 16px;\n            }\n\n            #cai-library-wrapper .cai-content-section {\n                padding: 24px;\n                border-radius: 20px;\n            }\n\n            #cai-library-wrapper .cai-modal-content {\n                width: 95%;\n                margin: 10% auto;\n                border-radius: 20px;\n            }\n\n            #cai-library-wrapper .cai-modal-header {\n                padding: 24px;\n            }\n\n            #cai-library-wrapper .cai-modal-body {\n                padding: 24px;\n            }\n        }\n    <\/style>\n<\/head>\n<body>\n    <div id=\"cai-library-wrapper\">\n        <div class=\"cai-container\">\n            <!-- Header -->\n            <div class=\"cai-header\" id=\"caiHeader\">\n                <h1>Videoteca CAI VOLPIANO<\/h1>\n                <span class=\"cai-update-date\">Aggiornamento Maggio 2014<\/span>\n                <div class=\"cai-info-warn\">\n                    <ul>\n                        <li>Le videocassette devono essere richieste al responsabile che provveder\u00e0 a compilare l&#8217;apposito registro.<\/li>\n                        <li>Il tempo massimo di visione \u00e8 di una settimana (da gioved\u00ec a gioved\u00ec).<\/li>\n                    <\/ul>\n                <\/div>\n            <\/div>\n\n            <div id=\"moviesByAuthor\">\n                <!-- Content populated by JavaScript -->\n            <\/div>\n\n            <div class=\"pagination\" id=\"pagination\">\n                <!-- Content populated by JavaScript -->\n            <\/div>\n\n            <div class=\"page-info\" id=\"pageInfo\"><\/div>\n        <\/div>\n\n        <!-- Modal -->\n        <div id=\"caiMovieModal\" class=\"cai-modal\">\n            <div id=\"caiMovieModalContent\" class=\"cai-modal-content\">\n                <div class=\"cai-modal-header\">\n                    <h2 id=\"caiModalDirectorName\">Libri dell&#8217;autore<\/h2>\n                    <button class=\"cai-close\">&times;<\/button>\n                <\/div>\n                <div class=\"cai-modal-body\">\n                    <ul class=\"cai-book-list\" id=\"caiMovieList\"><\/ul>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n    <script>\n        (function() {\n            const movieByDirector = [\n                {\n                    author: \"Amatoriale\",\n                    books: [\n                        { title: \"Discesa della Mer de Glace 27\/03\/97\", number: \"1\" },\n                        { title: \"Monte Bianco 1999\", number: \"2\" }\n                    ]\n                },\n                {\n                    author: \"National Geographic video\",\n                    books: [\n                        { title: \"Masai, i guerrieri della savana\", number: \"3\" },\n                        { title: \"Ritorno all'Everest\", number: \"4\" }\n                    ]\n                },\n                {\n                    author: \"I video di Alp\",\n                    books: [\n                        { title: \"The time machine, ritorno al futuro sugli sci\", number: \"5\" }\n                    ]\n                },\n                {\n                    author: \"Video Alp\",\n                    books: [\n                        { title: \"Dalla semplice passeggiata alle salite pi\u00f9 impegnative...\", number: \"6\" }\n                    ]\n                },\n                {\n                    author: \"RAI (registrata)\",\n                    books: [\n                        { title: \"Messner - 1987\", number: \"7\" },\n                        { title: \"Messner - 1987 : Valerio Bertoglio\", number: \"8\" }\n                    ]\n                },\n                {\n                    author: \"registrata\",\n                    books: [\n                        { title: \"La tragedia della parete nord dell'Eiger\", number: \"9\" },\n                        { title: \"Cinque giorni, un'estate 1982\", number: \"10\" },\n                        { title: \"Il rischio e il mio mestiere\", number: \"11\" }\n                    ]\n                },\n                {\n                    author: \"R. Messner\",\n                    books: [\n                        { title: \"L'hotze 8511m parete sud\", number: \"12\" }\n                    ]\n                },\n                {\n                    author: \"Jonathan dimensione avv.\",\n                    books: [\n                        { title: \"La montagna regno dell'avventura (Cerro Torre 85, Soccorso Alpino)\", number: \"13\" }\n                    ]\n                },\n                {\n                    author: \"Airone Video\",\n                    books: [\n                        { title: \"Il fiume scomparso\", number: \"14\" },\n                        { title: \"Vita sulle montagne di Maya\", number: \"15\" },\n                        { title: \"Il continente Bianco\", number: \"16\" }\n                    ]\n                },\n                {\n                    author: \"Conoscere le Alpi Video\",\n                    books: [\n                        { title: \"I giganti di granito\", number: \"17\" },\n                        { title: \"Il tetto della Svizzera\", number: \"18\" },\n                        { title: \"Nel regno dei 4000\", number: \"19\" },\n                        { title: \"Montagne incantate\", number: \"20\" },\n                        { title: \"Parco nazionale del Gran Paradiso in estate\", number: \"21\" },\n                        { title: \"I monti Pallidi\", number: \"22\" },\n                        { title: \"I balconi sulle Alpi\", number: \"23\" },\n                        { title: \"Nel cuore delle Alpi\", number: \"24\" }\n                    ]\n                },\n                {\n                    author: \"Natura d'Italia\",\n                    books: [\n                        { title: \"Il Gran Paradiso in Estate\", number: \"21bis\" }\n                    ]\n                },\n                {\n                    author: \"Regione siciliana\",\n                    books: [\n                        { title: \"Monte Conca\", number: \"25\" },\n                        { title: \"Grotta di Entella e grotta di Conza\", number: \"26\" }\n                    ]\n                },\n                {\n                    author: \"Folco Quilici (Atlante video)\",\n                    books: [\n                        { title: \"L'Amazzonia\", number: \"27\" }\n                    ]\n                },\n                {\n                    author: \"Specchio\",\n                    books: [\n                        { title: \"Alpi Cuore d'Europa\", number: \"28\" }\n                    ]\n                },\n                {\n                    author: \"CAI\",\n                    books: [\n                        { title: \"Tecnica di discesa nello sci alpinismo\", number: \"29\" },\n                        { title: \"???\", number: \"30\" }\n                    ]\n                },\n                {\n                    author: \"Unknown\",\n                    books: [\n                        { title: \"Parco Adamello Brenta\", number: \"31\" },\n                        { title: \"Progetto life Ursus\", number: \"32\" },\n                        { title: \"Il parco del Sile\", number: \"33\" },\n                        { title: \"Vento nel parco\", number: \"34\" },\n                        { title: \"Quel favoloso mondo dei bivacchi\", number: \"35\" },\n                        { title: \"Il colore dei ricordi\", number: \"36\" },\n                        { title: \"La grande cordata\", number: \"37\" },\n                        { title: \"Il Gran Sasso e i Monti della Laga\", number: \"38\" }\n                    ]\n                },\n                {\n                    author: \"PGNP\",\n                    books: [\n                        { title: \"Su il sipano sul Parco\", number: \"39\" }\n                    ]\n                }\n            ];\n\n            const ITEMS_PER_PAGE = 6;\n            const totalPageMovies = Math.ceil(movieByDirector.length \/ ITEMS_PER_PAGE);\n            let currentPage = 1;\n\n            let authorGrid = null;\n            \n            const paginator = document.getElementById('pagination');\n            const pageInfo = document.getElementById('pageInfo');\n            const modal = document.getElementById('caiMovieModal');\n            const modalContent = document.getElementById('caiMovieModalContent');\n            const modalAuthorName = document.getElementById('caiModalDirectorName');\n            const movieList = document.getElementById('caiMovieList');\n            const closeBtn = document.querySelector('#cai-library-wrapper .cai-close');\n            const moviesByAuthorSection = document.getElementById('moviesByAuthor');\n\n            function renderCards(page) {\n                \/\/ Fade out existing grid if it exists\n                const existingGrid = document.getElementById('caiDirectorGrid');\n                if (existingGrid) {\n                    existingGrid.classList.add('fade-out');\n                }\n\n                setTimeout(() => {\n                    moviesByAuthorSection.innerHTML = '';\n                    \n                    const startIndex = (page - 1) * ITEMS_PER_PAGE;\n                    const endIndex = startIndex + ITEMS_PER_PAGE;\n                    const pageItems = movieByDirector.slice(startIndex, endIndex);\n\n                    const authorContainer = document.createElement('div');\n                    authorContainer.classList.add('cai-content-section');\n\n                    authorContainer.innerHTML = `\n                        <div class=\"cai-author-grid\" id=\"caiDirectorGrid\">\n                            <!-- Content populated by JavaScript -->\n                        <\/div>\n                    `;\n\n                    moviesByAuthorSection.appendChild(authorContainer);\n                    \n                    populateDirectors(pageItems);\n                    renderDirectorPagination(totalPageMovies);\n                }, existingGrid ? 300 : 0);\n            } \n\n            function renderDirectorPagination(totalAuthorPage) {\n                const pagination = document.getElementById('pagination');\n                pagination.innerHTML = '';\n                let buttons = [];\n\n                buttons.push(`\n                    <button data-page=\"${currentPage - 1}\" ${currentPage === 1 ? 'disabled' : ''}>\n                        \u2190\n                    <\/button>\n                `);\n\n                if (totalAuthorPage <= 7) {\n                    for (let i = 1; i <= totalAuthorPage; i++) {\n                        buttons.push(`\n                            <button data-page=\"${i}\" class=\"${i === currentPage ? 'active' : ''}\">\n                                ${i}\n                            <\/button>\n                        `);\n                    }\n                } else {\n                    buttons.push(`\n                        <button data-page=\"1\" class=\"${currentPage === 1 ? 'active' : ''}\">1<\/button>\n                    `);\n\n                    if (currentPage > 3) {\n                        buttons.push('<span class=\"dots\">...<\/span>');\n                    }\n\n                    let startPage = Math.max(2, currentPage - 1);\n                    let endPage = Math.min(totalAuthorPage - 1, currentPage + 1);\n\n                    for (let i = startPage; i <= endPage; i++) {\n                        buttons.push(`\n                            <button data-page=\"${i}\" class=\"${i === currentPage ? 'active' : ''}\">\n                                ${i}\n                            <\/button>\n                        `);\n                    }\n\n                    if (currentPage < totalAuthorPage - 2) {\n                        buttons.push('<span class=\"dots\">...<\/span>');\n                    }\n\n                    buttons.push(`\n                        <button data-page=\"${totalAuthorPage}\" class=\"${currentPage === totalAuthorPage ? 'active' : ''}\">\n                            ${totalAuthorPage}\n                        <\/button>\n                    `);\n                }\n\n                buttons.push(`\n                    <button data-page=\"${currentPage + 1}\" ${currentPage === totalAuthorPage ? 'disabled' : ''}>\n                        \u2192\n                    <\/button>\n                `);\n\n                pagination.innerHTML = buttons.join('');\n\n                pagination.querySelectorAll('button').forEach(button => {\n                    button.addEventListener('click', function() {\n                        const page = parseInt(this.getAttribute('data-page'));\n                        if (page) {\n                            changeAuthorPage(page, totalAuthorPage);\n                        }\n                    });\n                });\n            }\n\n            function changeAuthorPage(page, totalDirectorPage) {\n                if (page < 1 || page > totalDirectorPage || page === currentPage) return;\n                currentPage = page;\n\n                renderCards(currentPage);\n            }\n\n            function populateDirectors(movieDataSliced) {\n                authorGrid = document.getElementById('caiDirectorGrid');\n                movieDataSliced.forEach((author) => {\n                    const card = document.createElement('div');\n                    card.className = 'cai-author-card';\n                    card.innerHTML = `\n                        <div class=\"cai-author-card-content\">\n                            <div class=\"cai-author-name\">\n                                <div class=\"cai-author-icon\">\ud83c\udfac<\/div>\n                                ${author.author}\n                            <\/div>\n                            <div class=\"cai-book-count-badge\">\n                                ${author.books.length} film\n                                <span class=\"arrow\">\u2192<\/span>\n                            <\/div>\n                        <\/div>\n                    `;\n                    card.addEventListener('click', () => showModal(author));\n                    authorGrid.appendChild(card);\n                });\n            }\n\n            function showModal(authorData) {\n                modalAuthorName.textContent = `Video di ${authorData.author}`;\n                movieList.innerHTML = '';\n\n                authorData.books.forEach(book => {\n                    const li = document.createElement('li');\n                    li.className = 'cai-book-item';\n                    li.innerHTML = `\n                        <span class=\"cai-book-title\">${book.title}<\/span>\n                        <span class=\"cai-book-number\">${book.number}<\/span>`;\n                    movieList.appendChild(li);\n                });\n\n                const scrollbarWidth = window.innerWidth - document.documentElement.clientWidth;\n                \n                const scrollY = window.scrollY || window.pageYOffset;\n                modalContent.style.position = 'relative';\n                modalContent.style.top = `${scrollY}px`;\n                \n                document.body.style.paddingRight = `${scrollbarWidth}px`;\n\n                modal.style.display = 'block';\n            }\n\n            function closeModal() {\n                modal.style.display = 'none';\n                document.body.style.overflow = '';\n            }\n\n            closeBtn.addEventListener('click', closeModal);\n\n            window.addEventListener('click', function(e) {\n                if (e.target === modal) {\n                    closeModal();\n                }\n            });\n\n            document.addEventListener('keydown', function(e) {\n                if (e.key === 'Escape' && modal.style.display === 'block') {\n                    closeModal();\n                }\n            });\n\n            \/\/ Initialize\n            renderCards(currentPage);\n        })();\n    <\/script>\n<\/body>\n<\/html>\n","protected":false},"excerpt":{"rendered":"<p>Videoteca CAI VOLPIANO Videoteca CAI VOLPIANO Aggiornamento Maggio 2014 Le videocassette devono essere richieste al responsabile che provveder\u00e0 a compilare l&#8217;apposito registro. Il tempo massimo di visione \u00e8 di una [&hellip;]<\/p>\n","protected":false},"author":414,"featured_media":36,"parent":528,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"rankMath":{"parentDomain":"organizzazione.cai.it","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"L&#039;immagine in evidenza dovrebbe essere di almeno 200 x 200 pixel per essere ripresa da Facebook e altri siti di social media.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"videoteca","permalinkFormat":"https:\/\/organizzazione.cai.it\/sez-volpiano\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":false,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"nome utente","primaryTerm":0,"authorName":"presidente@caivolpiano.it","titleTemplate":"%title% %sep% CAI %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":true},"homeUrl":"https:\/\/organizzazione.cai.it\/sez-volpiano","objectID":685,"objectType":"post","locale":"it","localeFull":"it_IT","overlayImages":{"play":{"name":"Icona di riproduzione","url":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/var\/www\/vhosts\/organizzazione.cai.it\/httpdocs\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Icona GIF","url":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/var\/www\/vhosts\/organizzazione.cai.it\/httpdocs\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-content\/uploads\/sites\/153\/2024\/09\/og.webp","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Forganizzazione.cai.it%2Fsez-volpiano&r=https%3A%2F%2Forganizzazione.cai.it%2Fsez-volpiano%2Fwp-json%2Fwp%2Fv2%2Fpages%2F685%3Fnonce%3D627daeff82","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAQCAYAAAAf8\/9hAAABs0lEQVR4AWL4\/\/8\/RRjO8Iucx+noO0MWUDo16FYABMGP6ZfUcRnWtm27jVPbtm3bttuH2t3eFPcY9pLz7NxiLjCyVd87pKnHyqXyxtCs8APd0rnyxiu4qSeA3QEDrAwBDrT1s1Rc\/OrjLZwqVmOSu6+Lamcpp2KKMA9PH1BYXMe1mUP5qotvXTywsOEEYHXxrY+3cqk6TMkYpNr2FeoY3KIr0RPtn9wQ2unlA+GMkRw6+9TFw4YTwDUzx\/JVvARj9KaedXRO8P5B1Du2S32smzqUrcKGEyA+uAgQjKX7zf0boWHGfn71jIKj2689gxp7OAGShNcBUmLMPVjZuiKcA2vuWHHDCQxMCz629kXAIU4ApY15QwggAFbfOP9DhgBJ+nWVJ1AZAfICAj1pAlY6hCADZnveQf7bQIwzVONGJonhLIlS9gr5mFg44Xd+4S3XHoGNPdJl1INIwKyEgHckEhgTe1bGiFY9GSFBYUwLh1IkiJUbY407E7syBSFxKTszEoiE\/YdrgCEayDmtaJwCI9uu8TKMuZSVfSa4BpGgzvomBR\/INhLGzrqDotp01ZR8pn\/1L0JN9d9XNyx0AAAAAElFTkSuQmCC","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Aggiorna","trendsPreviewImage":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-json\/wp\/v2\/pages\/685"}],"collection":[{"href":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-json\/wp\/v2\/users\/414"}],"replies":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-json\/wp\/v2\/comments?post=685"}],"version-history":[{"count":4,"href":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-json\/wp\/v2\/pages\/685\/revisions"}],"predecessor-version":[{"id":690,"href":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-json\/wp\/v2\/pages\/685\/revisions\/690"}],"up":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-json\/wp\/v2\/pages\/528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-json\/wp\/v2\/media\/36"}],"wp:attachment":[{"href":"https:\/\/organizzazione.cai.it\/sez-volpiano\/wp-json\/wp\/v2\/media?parent=685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}